{"id":2048,"date":"2019-11-12T17:53:57","date_gmt":"2019-11-12T17:53:57","guid":{"rendered":"http:\/\/www.apartamentosplaza.com\/web\/?p=2048"},"modified":"2019-11-12T17:54:09","modified_gmt":"2019-11-12T17:54:09","slug":"mercado-navideno-cordoba-2019","status":"publish","type":"post","link":"https:\/\/apartamentosplaza.com\/web\/index.php\/2019\/11\/12\/mercado-navideno-cordoba-2019\/","title":{"rendered":"Mercado Navide\u00f1o C\u00f3rdoba 2019"},"content":{"rendered":"\n[et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbAbout Us\u00bb _builder_version=\u00bb3.22.5&#8243; custom_padding=\u00bb0px||0px|||\u00bb][et_pb_row _builder_version=\u00bb3.25&#8243; custom_padding=\u00bb0px||0px|||\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb3.25&#8243; custom_padding=\u00bb|||\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text _builder_version=\u00bb3.27.4&#8243; custom_padding=\u00bb||0px|||\u00bb]\t\t<div id=\"sbi_mod_error\" >\n\t\t\t<span>Este mensaje de error solo es visible para los administradores de WordPress<\/span><br\/>\n\t\t\t<p><strong>Error: No se ha encontrado ning\u00fan feed.<\/strong>\n\t\t\t<p>Por favor, ve a la p\u00e1gina de ajustes de Instagram Feed para crear un feed.<\/p>\n\t\t<\/div>\n\t\t[\/et_pb_text][et_pb_social_media_follow _builder_version=\u00bb3.22.5&#8243;][et_pb_social_media_follow_network social_network=\u00bbfacebook\u00bb url=\u00bbhttps:\/\/www.facebook.com\/Apartamentos-Plaza-1701558410070402\/\u00bb _builder_version=\u00bb3.22.5&#8243; background_color=\u00bb#3b5998&#8243; follow_button=\u00bboff\u00bb url_new_window=\u00bbon\u00bb]facebook[\/et_pb_social_media_follow_network][et_pb_social_media_follow_network social_network=\u00bbinstagram\u00bb url=\u00bbhttps:\/\/www.instagram.com\/apartamentosplazacordoba\/\u00bb _builder_version=\u00bb3.22.5&#8243; background_color=\u00bb#ea2c59&#8243; follow_button=\u00bboff\u00bb url_new_window=\u00bbon\u00bb]instagram[\/et_pb_social_media_follow_network][\/et_pb_social_media_follow][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; next_background_color=\u00bb#000000&#8243; admin_label=\u00bbHeader\u00bb _builder_version=\u00bb3.22.3&#8243; use_background_color_gradient=\u00bbon\u00bb background_color_gradient_start=\u00bbrgba(0,37,68,0.7)\u00bb background_color_gradient_end=\u00bbrgba(0,37,68,0.5)\u00bb background_color_gradient_direction=\u00bb120deg\u00bb background_color_gradient_start_position=\u00bb60%\u00bb background_color_gradient_end_position=\u00bb60%\u00bb background_color_gradient_overlays_image=\u00bbon\u00bb background_image=\u00bbhttps:\/\/www.apartamentosplaza.com\/web\/wp-content\/uploads\/2019\/04\/soccer-11.jpg\u00bb custom_padding=\u00bb0vw|0px|0vw|0px|true|false\u00bb bottom_divider_style=\u00bbmountains2&#8243; bottom_divider_flip=\u00bbhorizontal\u00bb][et_pb_row _builder_version=\u00bb3.25&#8243; custom_width_px=\u00bb1280px\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb3.25&#8243; custom_padding=\u00bb|||\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text _builder_version=\u00bb3.27.4&#8243; text_font=\u00bbOpen Sans||||||||\u00bb text_font_size=\u00bb16px\u00bb text_line_height=\u00bb1.8em\u00bb header_font=\u00bbSquada One|||on|||||\u00bb header_font_size=\u00bb60px\u00bb header_letter_spacing=\u00bb1px\u00bb header_line_height=\u00bb1.1em\u00bb background_layout=\u00bbdark\u00bb max_width=\u00bb700px\u00bb custom_padding=\u00bb||0px|||\u00bb animation_style=\u00bbfade\u00bb text_font_size_tablet=\u00bb\u00bb text_font_size_phone=\u00bb\u00bb text_font_size_last_edited=\u00bbon|desktop\u00bb text_line_height_tablet=\u00bb\u00bb text_line_height_phone=\u00bb\u00bb text_line_height_last_edited=\u00bbon|desktop\u00bb header_font_size_tablet=\u00bb\u00bb header_font_size_phone=\u00bb32px\u00bb header_font_size_last_edited=\u00bbon|phone\u00bb]<h1>mercado navide\u00f1o c\u00f3rdoba 2019<\/h1>\n<p class=\"m_-904313370925301319p1\"><span class=\"m_-904313370925301319s1\">Este mes de noviembre C\u00f3rdoba ha inaugurado su mercado navide\u00f1o en la plaza mas c\u00e9ntrica y visitada de la ciudad \u00abLas Tendidas\u00bb. Su sexta edici\u00f3n con nuevos colaboraciones especiales.<\/span><\/p>[\/et_pb_text][et_pb_video src=\u00bbhttps:\/\/www.youtube.com\/watch?v=e2aaQyPSgDQ\u00bb image_src=\u00bb\/\/i.ytimg.com\/vi\/e2aaQyPSgDQ\/hqdefault.jpg\u00bb thumbnail_overlay_color=\u00bbrgba(0,0,0,0.6)\u00bb _builder_version=\u00bb4.0.6&#8243; custom_margin=\u00bb||0px\u00bb hover_enabled=\u00bb0&#8243; border_color_all=\u00bb#e09900&#8243; border_width_top=\u00bb8px\u00bb box_shadow_style=\u00bbpreset1&#8243; box_shadow_vertical=\u00bb20px\u00bb box_shadow_blur=\u00bb80px\u00bb box_shadow_spread=\u00bb-20px\u00bb box_shadow_color=\u00bb#000000&#8243;][\/et_pb_video][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbAnnouncement\u00bb _builder_version=\u00bb3.22.3&#8243; background_color=\u00bb#000000&#8243; custom_padding=\u00bb10px||10px||true\u00bb][et_pb_row _builder_version=\u00bb3.25&#8243; custom_padding=\u00bb0|0px|20px|0px|false|false\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb3.25&#8243; custom_padding=\u00bb|||\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text _builder_version=\u00bb4.0.6&#8243; text_font=\u00bb||||||||\u00bb header_font=\u00bb||||||||\u00bb header_4_font=\u00bbOpen Sans|700|||||||\u00bb header_4_font_size=\u00bb20px\u00bb header_4_line_height=\u00bb1.8em\u00bb background_layout=\u00bbdark\u00bb custom_margin=\u00bb||0px|\u00bb animation_style=\u00bbslide\u00bb animation_direction=\u00bbleft\u00bb animation_intensity_slide=\u00bb10%\u00bb hover_enabled=\u00bb0&#8243; header_4_line_height_tablet=\u00bb\u00bb header_4_line_height_phone=\u00bb\u00bb header_4_line_height_last_edited=\u00bbon|desktop\u00bb locked=\u00bboff\u00bb]<h4><span style=\"color: #00aaff;\">Fuente:<\/span>\u00a0<a href=\"https:\/\/www.youtube.com\/channel\/UCADr2Zpl7RmCqyd1rrEgxww\" target=\"_blank\" rel=\"noopener noreferrer\">Onda Mezquita TV<\/a><\/h4>\n[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbAbout Us\u00bb _builder_version=\u00bb3.22.3&#8243; background_color=\u00bb#f4f4f4&#8243;][et_pb_row _builder_version=\u00bb3.25&#8243; column_structure=\u00bb3_5,2_5&#8243;][et_pb_column type=\u00bb3_5&#8243; _builder_version=\u00bb3.25&#8243; custom_padding=\u00bb|||\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text _builder_version=\u00bb3.27.4&#8243; text_font=\u00bbOpen Sans||||||||\u00bb text_line_height=\u00bb1.8em\u00bb header_font=\u00bb||||||||\u00bb header_2_font=\u00bbSquada One||||||||\u00bb header_2_font_size=\u00bb40px\u00bb custom_margin=\u00bb||0px|\u00bb custom_padding=\u00bb40px||40px||true|false\u00bb header_2_font_size_tablet=\u00bb35px\u00bb header_2_font_size_phone=\u00bb25px\u00bb header_2_font_size_last_edited=\u00bbon|desktop\u00bb border_color_all=\u00bbrgba(0,0,0,0)\u00bb border_width_top=\u00bb8px\u00bb max_width__hover=\u00bb100%\u00bb max_width__hover_enabled=\u00bb100%\u00bb use_background_color_gradient__hover=\u00bboff\u00bb use_background_color_gradient__hover_enabled=\u00bboff\u00bb background_color_gradient_start__hover=\u00bb#2b87da\u00bb background_color_gradient_start__hover_enabled=\u00bb#2b87da\u00bb background_color_gradient_end__hover=\u00bb#29c4a9&#8243; background_color_gradient_end__hover_enabled=\u00bb#29c4a9&#8243; background_color_gradient_type__hover=\u00bblinear\u00bb background_color_gradient_type__hover_enabled=\u00bblinear\u00bb background_color_gradient_direction__hover=\u00bb180deg\u00bb background_color_gradient_direction__hover_enabled=\u00bb180deg\u00bb background_color_gradient_direction_radial__hover=\u00bbcenter\u00bb background_color_gradient_direction_radial__hover_enabled=\u00bbcenter\u00bb background_color_gradient_start_position__hover=\u00bb0%\u00bb background_color_gradient_start_position__hover_enabled=\u00bb0%\u00bb background_color_gradient_end_position__hover=\u00bb100%\u00bb background_color_gradient_end_position__hover_enabled=\u00bb100%\u00bb background_color_gradient_overlays_image__hover=\u00bboff\u00bb background_color_gradient_overlays_image__hover_enabled=\u00bboff\u00bb parallax__hover=\u00bboff\u00bb parallax__hover_enabled=\u00bboff\u00bb parallax_method__hover=\u00bbon\u00bb parallax_method__hover_enabled=\u00bbon\u00bb background_size__hover=\u00bbcover\u00bb background_size__hover_enabled=\u00bbcover\u00bb background_position__hover=\u00bbcenter\u00bb background_position__hover_enabled=\u00bbcenter\u00bb background_repeat__hover=\u00bbno-repeat\u00bb background_repeat__hover_enabled=\u00bbno-repeat\u00bb background_blend__hover=\u00bbnormal\u00bb background_blend__hover_enabled=\u00bbnormal\u00bb allow_player_pause__hover=\u00bboff\u00bb allow_player_pause__hover_enabled=\u00bboff\u00bb background_video_pause_outside_viewport__hover=\u00bbon\u00bb background_video_pause_outside_viewport__hover_enabled=\u00bbon\u00bb box_shadow_style__hover=\u00bbnone\u00bb box_shadow_style__hover_enabled=\u00bbnone\u00bb box_shadow_color__hover=\u00bbrgba(0,0,0,0.3)\u00bb box_shadow_color__hover_enabled=\u00bbrgba(0,0,0,0.3)\u00bb]<h2>\u00bfDe qu\u00e9 evento se trata?<\/h2>\n<p style=\"text-align: justify;\"><span>Como todos los a\u00f1os, el centro de C\u00f3rdoba se engalana en las semanas previas a la Navidad de forma especial para transmitir el sentimiento propio que rige en estas fechas. Este a\u00f1o, la c\u00e9ntrica <\/span><a href=\"https:\/\/www.cordoba24.info\/html\/plaza_tendillas.html\"><b>Plaza de las Tendillas<\/b><\/a><span> acoger\u00e1 por sexta vez el Mercado Navide\u00f1o Ciudad de C\u00f3rdoba que estar\u00e1 abierto del 8 de noviembre al 22 de diciembre de 2019. <\/span><\/p>\n<p><span>Organizado por la Asociaci\u00f3n Cultural Belenista, el Mercado de Navidad contar\u00e1 con la participaci\u00f3n de m\u00e1s de veinte empresas de toda la geograf\u00eda espa\u00f1ola que ocupan un total de 45 caba\u00f1as.<\/span><\/p>\n<p>En total, una veintena de empresas ser\u00e1 la que conforme el Mercado. Los dos requisitos principales que impone la Asociaci\u00f3n Belenista de C\u00f3rdoba a los empresarios que quieren formar parte de este peque\u00f1o bazar son: una higiene muy exhaustiva y que, en la medida de lo posible, sus productos supongan una promoci\u00f3n de la ciudad.<\/p>\n<p>Indistintamente, el Mercado seguir\u00e1 ofreciendo dulces\u00a0t\u00edpicos como bu\u00f1uelos, gofres y garrapi\u00f1adas y dem\u00e1s alimentos a los que se unir\u00e1n productos de diferentes partes de Espa\u00f1a. Como es tradici\u00f3n, la Asociaci\u00f3n Belenista de C\u00f3rdoba tambi\u00e9n potencia la difusi\u00f3n de otros manjares espa\u00f1oles, como fueron los productos gallegos, quesos malague\u00f1os y embutidos de Extremadura de anteriores ediciones del Mercado.<\/p>\n<p><span style=\"font-size: 14px;\">Para los m\u00e1s peque\u00f1os habr\u00e1 una serie de actividades infantiles donde destacan el teatro y la magia. Tambi\u00e9n habr\u00e1 un bel\u00e9n de seis por dos metros y un \u00e1rbol de navidad. Cabe destacar, que junto al mercado navide\u00f1o, en la calle Cruz Conde, habr\u00e1 por primera vez en C\u00f3rdoba un espect\u00e1culo navide\u00f1o de luces y m\u00fasica.<\/span><\/p>\n<p style=\"text-align: justify;\"><\/p>[\/et_pb_text][et_pb_text _builder_version=\u00bb3.27.4&#8243; text_font=\u00bbOpen Sans||||||||\u00bb text_line_height=\u00bb1.8em\u00bb header_font=\u00bb||||||||\u00bb header_2_font=\u00bbSquada One||||||||\u00bb header_2_font_size=\u00bb40px\u00bb custom_margin=\u00bb||0px|\u00bb custom_padding=\u00bb40px||40px||true|false\u00bb header_2_font_size_tablet=\u00bb35px\u00bb header_2_font_size_phone=\u00bb25px\u00bb header_2_font_size_last_edited=\u00bbon|desktop\u00bb border_color_all=\u00bbrgba(0,0,0,0)\u00bb border_width_top=\u00bb8px\u00bb max_width__hover=\u00bb100%\u00bb max_width__hover_enabled=\u00bb100%\u00bb use_background_color_gradient__hover=\u00bboff\u00bb use_background_color_gradient__hover_enabled=\u00bboff\u00bb background_color_gradient_start__hover=\u00bb#2b87da\u00bb background_color_gradient_start__hover_enabled=\u00bb#2b87da\u00bb background_color_gradient_end__hover=\u00bb#29c4a9&#8243; background_color_gradient_end__hover_enabled=\u00bb#29c4a9&#8243; background_color_gradient_type__hover=\u00bblinear\u00bb background_color_gradient_type__hover_enabled=\u00bblinear\u00bb background_color_gradient_direction__hover=\u00bb180deg\u00bb background_color_gradient_direction__hover_enabled=\u00bb180deg\u00bb background_color_gradient_direction_radial__hover=\u00bbcenter\u00bb background_color_gradient_direction_radial__hover_enabled=\u00bbcenter\u00bb background_color_gradient_start_position__hover=\u00bb0%\u00bb background_color_gradient_start_position__hover_enabled=\u00bb0%\u00bb background_color_gradient_end_position__hover=\u00bb100%\u00bb background_color_gradient_end_position__hover_enabled=\u00bb100%\u00bb background_color_gradient_overlays_image__hover=\u00bboff\u00bb background_color_gradient_overlays_image__hover_enabled=\u00bboff\u00bb parallax__hover=\u00bboff\u00bb parallax__hover_enabled=\u00bboff\u00bb parallax_method__hover=\u00bbon\u00bb parallax_method__hover_enabled=\u00bbon\u00bb background_size__hover=\u00bbcover\u00bb background_size__hover_enabled=\u00bbcover\u00bb background_position__hover=\u00bbcenter\u00bb background_position__hover_enabled=\u00bbcenter\u00bb background_repeat__hover=\u00bbno-repeat\u00bb background_repeat__hover_enabled=\u00bbno-repeat\u00bb background_blend__hover=\u00bbnormal\u00bb background_blend__hover_enabled=\u00bbnormal\u00bb allow_player_pause__hover=\u00bboff\u00bb allow_player_pause__hover_enabled=\u00bboff\u00bb background_video_pause_outside_viewport__hover=\u00bbon\u00bb background_video_pause_outside_viewport__hover_enabled=\u00bbon\u00bb box_shadow_style__hover=\u00bbnone\u00bb box_shadow_style__hover_enabled=\u00bbnone\u00bb box_shadow_color__hover=\u00bbrgba(0,0,0,0.3)\u00bb box_shadow_color__hover_enabled=\u00bbrgba(0,0,0,0.3)\u00bb]<h2>Fechas y horarios<\/h2>\n<p style=\"text-align: justify;\"><span>El <strong><span style=\"color: #e09900;\">Mercado Navide\u00f1o <\/span><\/strong>permanecer\u00e1 abierto hasta el pr\u00f3ximo 22 de diciembre en horario de lunes a jueves, de 10:30 a 14:30 y de 17:00 a 21:00, mientras que los viernes el horario es de 10:00 a 23:00. Los domingos, por su parte, abre de 10:00 a 21:00.<\/span><\/p>\n<p style=\"text-align: justify;\">Puedes asistir visitandolo en la Plaza de las Tendillas, sino sabes llegar pulsa <a href=\"https:\/\/www.google.com\/search?client=safari&amp;rls=en&amp;q=como+llegar+tendillas+cordobas&amp;ie=UTF-8&amp;oe=UTF-8#\">aqu\u00ed<\/a>.<span><\/span><\/p>\n<p style=\"text-align: justify;\"><\/p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb2_5&#8243; _builder_version=\u00bb3.25&#8243; custom_padding=\u00bb|||\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text _builder_version=\u00bb3.27.4&#8243; text_font=\u00bbOpen Sans||||||||\u00bb text_line_height=\u00bb1.8em\u00bb header_font=\u00bb||||||||\u00bb header_2_font=\u00bbSquada One||||||||\u00bb header_2_font_size=\u00bb40px\u00bb background_color=\u00bb#ffffff\u00bb custom_margin=\u00bb40px||0px|\u00bb custom_padding=\u00bb0px|40px|0px|40px|true|true\u00bb header_2_font_size_tablet=\u00bb35px\u00bb header_2_font_size_phone=\u00bb25px\u00bb header_2_font_size_last_edited=\u00bbon|desktop\u00bb border_color_all=\u00bb#e09900&#8243; border_width_top=\u00bb8px\u00bb box_shadow_style=\u00bbpreset1&#8243; box_shadow_blur=\u00bb100px\u00bb box_shadow_color=\u00bbrgba(0,0,0,0.1)\u00bb locked=\u00bboff\u00bb max_width__hover=\u00bb100%\u00bb max_width__hover_enabled=\u00bb100%\u00bb]<h2>Mercado Navide\u00f1o C\u00f3rdoba<span style=\"font-size: 14px; font-family: 'Open Sans', Helvetica, Arial, Lucida, sans-serif; color: #666666;\">\u00a0<\/span><\/h2>[\/et_pb_text][et_pb_image src=\u00bbhttps:\/\/www.apartamentosplaza.com\/web\/wp-content\/uploads\/2019\/11\/1184856_1.jpg\u00bb align_tablet=\u00bbcenter\u00bb align_phone=\u00bb\u00bb align_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.0.6&#8243; custom_padding=\u00bb||120px\u00bb hover_enabled=\u00bb0&#8243;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbGallery \u00bb _builder_version=\u00bb3.22.7&#8243; background_color=\u00bb#18252c\u00bb custom_margin=\u00bb0px||\u00bb custom_padding=\u00bb0px|0px|0px|0px|true|false\u00bb][et_pb_row use_custom_gutter=\u00bbon\u00bb gutter_width=\u00bb1&#8243; module_class=\u00bb et_pb_row_fullwidth\u00bb _builder_version=\u00bb3.25&#8243; width=\u00bb100%\u00bb width_tablet=\u00bb100%\u00bb width_phone=\u00bb\u00bb width_last_edited=\u00bbon|desktop\u00bb max_width=\u00bb100%\u00bb max_width_tablet=\u00bb100%\u00bb max_width_phone=\u00bb\u00bb max_width_last_edited=\u00bbon|desktop\u00bb custom_padding=\u00bb0|0px|0|0px|true|false\u00bb make_fullwidth=\u00bbon\u00bb column_structure=\u00bb1_4,1_4,1_2&#8243;][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb3.25&#8243; custom_padding=\u00bb|||\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_image src=\u00bbhttps:\/\/www.apartamentosplaza.com\/web\/wp-content\/uploads\/2019\/11\/puestos-figuras-belenes_1190291046_74708232_667x375.jpg\u00bb show_in_lightbox=\u00bbon\u00bb use_overlay=\u00bbon\u00bb overlay_icon_color=\u00bb#ffffff\u00bb hover_overlay_color=\u00bbrgba(255,255,255,0.1)\u00bb align_tablet=\u00bbcenter\u00bb align_phone=\u00bb\u00bb align_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.0.6&#8243; custom_margin=\u00bb|0px||\u00bb custom_margin_last_edited=\u00bboff|desktop\u00bb animation_style=\u00bbzoom\u00bb animation_intensity_zoom=\u00bb20%\u00bb hover_enabled=\u00bb0&#8243; custom_margin__hover=\u00bb|||\u00bb][\/et_pb_image][et_pb_image src=\u00bbhttps:\/\/www.apartamentosplaza.com\/web\/wp-content\/uploads\/2019\/11\/997648_1.jpg\u00bb show_in_lightbox=\u00bbon\u00bb use_overlay=\u00bbon\u00bb overlay_icon_color=\u00bb#ffffff\u00bb hover_overlay_color=\u00bbrgba(255,255,255,0.1)\u00bb force_fullwidth=\u00bbon\u00bb align_tablet=\u00bbcenter\u00bb align_phone=\u00bb\u00bb align_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.0.6&#8243; max_width_tablet=\u00bb100%\u00bb max_width_phone=\u00bb\u00bb max_width_last_edited=\u00bbon|tablet\u00bb module_alignment=\u00bbright\u00bb custom_margin=\u00bb-10px||\u00bb custom_margin_tablet=\u00bb0px||\u00bb custom_margin_phone=\u00bb\u00bb custom_margin_last_edited=\u00bbon|desktop\u00bb animation_style=\u00bbzoom\u00bb animation_intensity_zoom=\u00bb20%\u00bb hover_enabled=\u00bb0&#8243; box_shadow_style=\u00bbpreset1&#8243; box_shadow_vertical=\u00bb0px\u00bb box_shadow_blur=\u00bb100px\u00bb box_shadow_spread=\u00bb50px\u00bb box_shadow_color=\u00bbrgba(0,0,0,0.8)\u00bb locked=\u00bboff\u00bb custom_margin__hover_enabled=\u00bbon\u00bb custom_margin__hover=\u00bb-20px||\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb3.25&#8243; custom_padding=\u00bb|||\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_image src=\u00bbhttps:\/\/www.apartamentosplaza.com\/web\/wp-content\/uploads\/2019\/11\/1512843179_000302_1512844263_noticia_normal.jpg\u00bb show_in_lightbox=\u00bbon\u00bb use_overlay=\u00bbon\u00bb overlay_icon_color=\u00bb#ffffff\u00bb hover_overlay_color=\u00bbrgba(255,255,255,0.1)\u00bb align_tablet=\u00bbcenter\u00bb align_phone=\u00bb\u00bb align_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.0.6&#8243; custom_margin=\u00bb-40px||\u00bb custom_margin_tablet=\u00bb0px||\u00bb custom_margin_phone=\u00bb\u00bb custom_margin_last_edited=\u00bbon|desktop\u00bb animation_style=\u00bbzoom\u00bb animation_intensity_zoom=\u00bb20%\u00bb hover_enabled=\u00bb0&#8243; locked=\u00bboff\u00bb custom_margin__hover_enabled=\u00bbon\u00bb custom_margin__hover=\u00bb-50px||\u00bb][\/et_pb_image][et_pb_image src=\u00bbhttps:\/\/www.apartamentosplaza.com\/web\/wp-content\/uploads\/2019\/11\/1184856_1.jpg\u00bb show_in_lightbox=\u00bbon\u00bb use_overlay=\u00bbon\u00bb overlay_icon_color=\u00bb#ffffff\u00bb hover_overlay_color=\u00bbrgba(255,255,255,0.1)\u00bb force_fullwidth=\u00bbon\u00bb align_tablet=\u00bbcenter\u00bb align_phone=\u00bb\u00bb align_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.0.6&#8243; custom_margin=\u00bb|||\u00bb custom_margin_tablet=\u00bb0px|||0px\u00bb custom_margin_phone=\u00bb\u00bb custom_margin_last_edited=\u00bbon|desktop\u00bb animation_style=\u00bbzoom\u00bb animation_intensity_zoom=\u00bb20%\u00bb hover_enabled=\u00bb0&#8243; box_shadow_style=\u00bbpreset1&#8243; box_shadow_vertical=\u00bb0px\u00bb box_shadow_blur=\u00bb100px\u00bb box_shadow_spread=\u00bb50px\u00bb box_shadow_color=\u00bbrgba(0,0,0,0.8)\u00bb locked=\u00bboff\u00bb custom_margin__hover_enabled=\u00bbon\u00bb custom_margin__hover=\u00bb-20px|||\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb3.25&#8243; custom_padding=\u00bb|||\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_image src=\u00bbhttps:\/\/www.apartamentosplaza.com\/web\/wp-content\/uploads\/2019\/11\/mercado_navideno.jpg\u00bb show_in_lightbox=\u00bbon\u00bb use_overlay=\u00bbon\u00bb overlay_icon_color=\u00bb#ffffff\u00bb hover_overlay_color=\u00bbrgba(255,255,255,0.1)\u00bb force_fullwidth=\u00bbon\u00bb align_tablet=\u00bbcenter\u00bb align_phone=\u00bb\u00bb align_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.0.6&#8243; custom_margin=\u00bb-80px||\u00bb custom_margin_tablet=\u00bb0px||\u00bb custom_margin_phone=\u00bb\u00bb custom_margin_last_edited=\u00bbon|desktop\u00bb animation_style=\u00bbzoom\u00bb animation_intensity_zoom=\u00bb20%\u00bb hover_enabled=\u00bb0&#8243; box_shadow_style=\u00bbpreset1&#8243; box_shadow_vertical=\u00bb0px\u00bb box_shadow_blur=\u00bb100px\u00bb box_shadow_spread=\u00bb50px\u00bb box_shadow_color=\u00bbrgba(0,0,0,0.8)\u00bb locked=\u00bboff\u00bb custom_margin__hover_enabled=\u00bbon\u00bb custom_margin__hover=\u00bb|||-20px\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbPrograms\u00bb _builder_version=\u00bb3.22.3&#8243; background_color=\u00bb#18252c\u00bb custom_padding=\u00bb39px|0px|0|0px|false|false\u00bb][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbOur Story\u00bb _builder_version=\u00bb3.22.7&#8243; background_color=\u00bb#f4f4f4&#8243; custom_margin=\u00bb-30px||\u00bb custom_padding=\u00bb||30px\u00bb][et_pb_row admin_label=\u00bbAbout The Divi United Club Row\u00bb _builder_version=\u00bb3.25&#8243; background_color=\u00bb#ffffff\u00bb width=\u00bb100%\u00bb custom_margin=\u00bb25px|auto|25px|auto|true|\u00bb custom_padding=\u00bb40px|40px|30px|40px|false|false\u00bb border_color_all=\u00bb#e09900&#8243; border_width_top=\u00bb8px\u00bb box_shadow_style=\u00bbpreset1&#8243; box_shadow_blur=\u00bb100px\u00bb box_shadow_color=\u00bbrgba(0,0,0,0.1)\u00bb locked=\u00bboff\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb3.25&#8243; custom_padding=\u00bb|||\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text _builder_version=\u00bb3.27.4&#8243; text_font=\u00bbOpen Sans||||||||\u00bb text_line_height=\u00bb1.8em\u00bb header_font=\u00bb||||||||\u00bb header_2_font=\u00bbSquada One||||||||\u00bb header_2_font_size=\u00bb40px\u00bb custom_margin=\u00bb||0px|\u00bb header_2_font_size_tablet=\u00bb35px\u00bb header_2_font_size_phone=\u00bb25px\u00bb header_2_font_size_last_edited=\u00bbon|desktop\u00bb border_color_all=\u00bbrgba(0,0,0,0)\u00bb border_width_top=\u00bb8px\u00bb box_shadow_style__hover=\u00bbnone\u00bb box_shadow_style__hover_enabled=\u00bbnone\u00bb box_shadow_color__hover=\u00bbrgba(0,0,0,0.3)\u00bb box_shadow_color__hover_enabled=\u00bbrgba(0,0,0,0.3)\u00bb max_width__hover=\u00bb100%\u00bb max_width__hover_enabled=\u00bb100%\u00bb use_background_color_gradient__hover=\u00bboff\u00bb use_background_color_gradient__hover_enabled=\u00bboff\u00bb background_color_gradient_start__hover=\u00bb#2b87da\u00bb background_color_gradient_start__hover_enabled=\u00bb#2b87da\u00bb background_color_gradient_end__hover=\u00bb#29c4a9&#8243; background_color_gradient_end__hover_enabled=\u00bb#29c4a9&#8243; background_color_gradient_type__hover=\u00bblinear\u00bb background_color_gradient_type__hover_enabled=\u00bblinear\u00bb background_color_gradient_direction__hover=\u00bb180deg\u00bb background_color_gradient_direction__hover_enabled=\u00bb180deg\u00bb background_color_gradient_direction_radial__hover=\u00bbcenter\u00bb background_color_gradient_direction_radial__hover_enabled=\u00bbcenter\u00bb background_color_gradient_start_position__hover=\u00bb0%\u00bb background_color_gradient_start_position__hover_enabled=\u00bb0%\u00bb background_color_gradient_end_position__hover=\u00bb100%\u00bb background_color_gradient_end_position__hover_enabled=\u00bb100%\u00bb background_color_gradient_overlays_image__hover=\u00bboff\u00bb background_color_gradient_overlays_image__hover_enabled=\u00bboff\u00bb parallax__hover=\u00bboff\u00bb parallax__hover_enabled=\u00bboff\u00bb parallax_method__hover=\u00bbon\u00bb parallax_method__hover_enabled=\u00bbon\u00bb background_size__hover=\u00bbcover\u00bb background_size__hover_enabled=\u00bbcover\u00bb background_position__hover=\u00bbcenter\u00bb background_position__hover_enabled=\u00bbcenter\u00bb background_repeat__hover=\u00bbno-repeat\u00bb background_repeat__hover_enabled=\u00bbno-repeat\u00bb background_blend__hover=\u00bbnormal\u00bb background_blend__hover_enabled=\u00bbnormal\u00bb allow_player_pause__hover=\u00bboff\u00bb allow_player_pause__hover_enabled=\u00bboff\u00bb background_video_pause_outside_viewport__hover=\u00bbon\u00bb background_video_pause_outside_viewport__hover_enabled=\u00bbon\u00bb]<h2>COLABORADORES Y PUESTOS<\/h2>[\/et_pb_text][et_pb_text _builder_version=\u00bb3.27.4&#8243; text_font=\u00bbOpen Sans||||||||\u00bb text_line_height=\u00bb1.8em\u00bb header_font=\u00bb||||||||\u00bb header_2_font=\u00bbSquada One||||||||\u00bb header_2_font_size=\u00bb40px\u00bb custom_margin=\u00bb||0px|\u00bb custom_padding=\u00bb3px||3px||true|false\u00bb header_2_font_size_tablet=\u00bb35px\u00bb header_2_font_size_phone=\u00bb25px\u00bb header_2_font_size_last_edited=\u00bbon|desktop\u00bb border_color_all=\u00bbrgba(0,0,0,0)\u00bb border_width_top=\u00bb8px\u00bb max_width__hover=\u00bb100%\u00bb max_width__hover_enabled=\u00bb100%\u00bb use_background_color_gradient__hover=\u00bboff\u00bb use_background_color_gradient__hover_enabled=\u00bboff\u00bb background_color_gradient_start__hover=\u00bb#2b87da\u00bb background_color_gradient_start__hover_enabled=\u00bb#2b87da\u00bb background_color_gradient_end__hover=\u00bb#29c4a9&#8243; background_color_gradient_end__hover_enabled=\u00bb#29c4a9&#8243; background_color_gradient_type__hover=\u00bblinear\u00bb background_color_gradient_type__hover_enabled=\u00bblinear\u00bb background_color_gradient_direction__hover=\u00bb180deg\u00bb background_color_gradient_direction__hover_enabled=\u00bb180deg\u00bb background_color_gradient_direction_radial__hover=\u00bbcenter\u00bb background_color_gradient_direction_radial__hover_enabled=\u00bbcenter\u00bb background_color_gradient_start_position__hover=\u00bb0%\u00bb background_color_gradient_start_position__hover_enabled=\u00bb0%\u00bb background_color_gradient_end_position__hover=\u00bb100%\u00bb background_color_gradient_end_position__hover_enabled=\u00bb100%\u00bb background_color_gradient_overlays_image__hover=\u00bboff\u00bb background_color_gradient_overlays_image__hover_enabled=\u00bboff\u00bb parallax__hover=\u00bboff\u00bb parallax__hover_enabled=\u00bboff\u00bb parallax_method__hover=\u00bbon\u00bb parallax_method__hover_enabled=\u00bbon\u00bb background_size__hover=\u00bbcover\u00bb background_size__hover_enabled=\u00bbcover\u00bb background_position__hover=\u00bbcenter\u00bb background_position__hover_enabled=\u00bbcenter\u00bb background_repeat__hover=\u00bbno-repeat\u00bb background_repeat__hover_enabled=\u00bbno-repeat\u00bb background_blend__hover=\u00bbnormal\u00bb background_blend__hover_enabled=\u00bbnormal\u00bb allow_player_pause__hover=\u00bboff\u00bb allow_player_pause__hover_enabled=\u00bboff\u00bb background_video_pause_outside_viewport__hover=\u00bbon\u00bb background_video_pause_outside_viewport__hover_enabled=\u00bbon\u00bb box_shadow_style__hover=\u00bbnone\u00bb box_shadow_style__hover_enabled=\u00bbnone\u00bb box_shadow_color__hover=\u00bbrgba(0,0,0,0.3)\u00bb box_shadow_color__hover_enabled=\u00bbrgba(0,0,0,0.3)\u00bb]<p><b>A continuaci\u00f3n te dejamos un listado con las empresas participantes:<\/b><\/p>\n<p>&nbsp;<\/p>\n<table width=\"100%\" border=\"0\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td align=\"CENTER\">\n<table id=\"Tabelle22\" border=\"0\" cellspacing=\"0\" cellpadding=\"0\" width=\"545\">\n<tbody>\n<tr>\n<td width=\"229\">\n<p><b>Empresa<br \/><\/b>\u00a0<\/p>\n<\/td>\n<td width=\"315\">\n<p><b>Producto<br \/><\/b>\u00a0<\/p>\n<\/td>\n<\/tr>\n<tr valign=\"TOP\">\n<td>\n<p>Artesan\u00eda de Corcho (Sevilla)<br \/>Artesan\u00eda Piel de Ubr\u00edque (C\u00e1diz)<br \/>Artesanos de la Piedra<br \/>Belenes Chirivella (Valencia)<br \/>Belenes Gloria Botonero (Sevilla)<br \/>Belenes La Adoraci\u00f3n (Lucena)<br \/>Belenes San Juli\u00e1n (Sevilla)<br \/>Casitas de Aroma (Sevilla)<br \/>Claire Creaciones (C\u00f3rdoba)<br \/>Dulces Migarlo (Zaragoza)<br \/>El Mago del Tenedor (Sevilla)<br \/>El Sabor de lo Artesano (Lucena)<br \/>\u00c1loe Vida (Mallorca)<br \/>Globos Tifani(C\u00f3rdoba)<br \/>La Creper\u00eda (Ja\u00e9n)<br \/>Golosina Gourmet (C\u00f3rdoba)<br \/>Ib\u00e9ricos en tu Mesa (Badajoz)<br \/>Madera de Olivo (Zaragoza)<br \/>Miniaturas Rogel (Priego de C\u00f3rdoba)<br \/>Oriente Exquisito (Cantabr\u00eda)<br \/>Oro Vegetal (Portugal)<br \/>Panader\u00eda artesana gallega (Galicia)<br \/>Perfumes Rubio (C\u00f3rdoba)<\/p>\n<\/td>\n<td>\n<p>Bolsos y monederos<br \/>Bolsos y monederos<br \/>Piedras y complementos<br \/>Belenes, figuras y miniaturas<br \/>Figuras de bel\u00e9n<br \/>Belenes, miniaturas y miniaturas<br \/>Figuras de bel\u00e9n<br \/>Casitas arom\u00e1ticas y quemadores de aceites <br \/>Artesan\u00eda de arcilla polim\u00e9rica<br \/>Garrapi\u00f1ada y barquillos artesanos<br \/>Artesan\u00eda con tenedores<br \/>Dulces y turrones<br \/>Productos ecol\u00f3gicos a base de \u00e1loe vera<br \/>Globos decorativos<br \/>Gofres y cr\u00eapes<br \/>Gominola, bu\u00f1uelos, palomitas y algod\u00f3n<br \/>Quesos, embutidos y jamones de Extremadura<br \/>Menaje de hogar y art\u00edculos en madera de olivo<br \/>Complementos para belenes<br \/>Frutos deshidratados<br \/>Bisuter\u00eda ecol\u00f3gica artesanal<br \/>Pan y dulces<br \/>Perfumes<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Desde Apartamentos tur\u00edsticos de C\u00f3rdoba \u00ab<a href=\"https:\/\/www.apartamentosplaza.com\">Apartamentos Plaza<\/a>\u00ab, estaremos encantados de alojarte para esta fecha o cualquier otra. Por ello si est\u00e1s interesado en visitar este evento pero a\u00fan no dispones de lugar donde quedarte, estar\u00edamos orgullosos de poder ser tus anfitriones.<\/p>\n<p>Visita nuestra apartado de <a href=\"https:\/\/www.apartamentosplaza.com\/web\/index.php\/contacto\/\" target=\"_blank\" rel=\"noopener noreferrer\">Contacto<\/a> o bien usa estos datos para ello.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><strong>APARTAMENTOS PLAZA<\/strong><span style=\"font-size: 14px; text-align: left;\">\u00a0<\/span><\/p>\n<p style=\"text-align: center;\">Plaza del Potro, 15 \u2013 14002 C\u00f3rdoba<\/p>\n<p style=\"text-align: center;\"><span>Calle Romero Barros 4-6, 14003 C\u00f3rdoba<\/span><\/p>\n<p style=\"text-align: center;\">T: +34 957 49 82 22<span style=\"font-size: 14px; text-align: left;\">\u00a0<\/span><\/p>\n<p style=\"text-align: center;\">M: +34 744 465 446<span style=\"font-size: 14px; text-align: left;\">\u00a0<\/span><\/p>\n<p style=\"text-align: center;\"><a href=\"mailto:reservas@apartamentosplaza.com\">reservas@apartamentosplaza.com<\/a><span style=\"font-size: 14px; text-align: left;\">\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p>Nuestro personal estar\u00e1 encantado de poder informarte m\u00e1s sobre \u00e9ste o cualquier otro evento.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]\n","protected":false},"excerpt":{"rendered":"<p>Este mes de noviembre se ha inciado el mercado navide\u00f1o de C\u00f3rdoba, \u00bfsabes donde est\u00e1, sus horarios y las novedades de este a\u00f1o? Apartamentos Plaza informa<\/p>\n","protected":false},"author":1,"featured_media":2052,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[33,7],"tags":[77,76],"class_list":["post-2048","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventos","category-fiestas","tag-mercado","tag-navidad"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mercado Navide\u00f1o C\u00f3rdoba 2019 - Apartamentos Plaza<\/title>\n<meta name=\"description\" content=\"Este mes de noviembre se ha inciado el mercado navide\u00f1o de C\u00f3rdoba, \u00bfsabes donde est\u00e1, sus horarios y las novedades de este a\u00f1o? Apartamentos Plaza informa\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/apartamentosplaza.com\/web\/index.php\/2019\/11\/12\/mercado-navideno-cordoba-2019\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mercado Navide\u00f1o C\u00f3rdoba 2019 - Apartamentos Plaza\" \/>\n<meta property=\"og:description\" content=\"Este mes de noviembre se ha inciado el mercado navide\u00f1o de C\u00f3rdoba, \u00bfsabes donde est\u00e1, sus horarios y las novedades de este a\u00f1o? Apartamentos Plaza informa\" \/>\n<meta property=\"og:url\" content=\"https:\/\/apartamentosplaza.com\/web\/index.php\/2019\/11\/12\/mercado-navideno-cordoba-2019\/\" \/>\n<meta property=\"og:site_name\" content=\"Apartamentos Plaza\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/apartamentosplazacordoba\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-11-12T17:53:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-11-12T17:54:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/apartamentosplaza.com\/web\/wp-content\/uploads\/2019\/11\/mercado_navideno.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"545\" \/>\n\t<meta property=\"og:image:height\" content=\"350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"apartamentosplaza\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"apartamentosplaza\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"16 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/index.php\\\/2019\\\/11\\\/12\\\/mercado-navideno-cordoba-2019\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/index.php\\\/2019\\\/11\\\/12\\\/mercado-navideno-cordoba-2019\\\/\"},\"author\":{\"name\":\"apartamentosplaza\",\"@id\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/#\\\/schema\\\/person\\\/e29015ac64546f50bb06fb4f6921c2c2\"},\"headline\":\"Mercado Navide\u00f1o C\u00f3rdoba 2019\",\"datePublished\":\"2019-11-12T17:53:57+00:00\",\"dateModified\":\"2019-11-12T17:54:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/index.php\\\/2019\\\/11\\\/12\\\/mercado-navideno-cordoba-2019\\\/\"},\"wordCount\":3262,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/index.php\\\/2019\\\/11\\\/12\\\/mercado-navideno-cordoba-2019\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/mercado_navideno.jpg\",\"keywords\":[\"mercado\",\"navidad\"],\"articleSection\":[\"Eventos\",\"Fiestas\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/index.php\\\/2019\\\/11\\\/12\\\/mercado-navideno-cordoba-2019\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/index.php\\\/2019\\\/11\\\/12\\\/mercado-navideno-cordoba-2019\\\/\",\"url\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/index.php\\\/2019\\\/11\\\/12\\\/mercado-navideno-cordoba-2019\\\/\",\"name\":\"Mercado Navide\u00f1o C\u00f3rdoba 2019 - Apartamentos Plaza\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/index.php\\\/2019\\\/11\\\/12\\\/mercado-navideno-cordoba-2019\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/index.php\\\/2019\\\/11\\\/12\\\/mercado-navideno-cordoba-2019\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/mercado_navideno.jpg\",\"datePublished\":\"2019-11-12T17:53:57+00:00\",\"dateModified\":\"2019-11-12T17:54:09+00:00\",\"description\":\"Este mes de noviembre se ha inciado el mercado navide\u00f1o de C\u00f3rdoba, \u00bfsabes donde est\u00e1, sus horarios y las novedades de este a\u00f1o? Apartamentos Plaza informa\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/index.php\\\/2019\\\/11\\\/12\\\/mercado-navideno-cordoba-2019\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/index.php\\\/2019\\\/11\\\/12\\\/mercado-navideno-cordoba-2019\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/index.php\\\/2019\\\/11\\\/12\\\/mercado-navideno-cordoba-2019\\\/#primaryimage\",\"url\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/mercado_navideno.jpg\",\"contentUrl\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/mercado_navideno.jpg\",\"width\":545,\"height\":350},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/index.php\\\/2019\\\/11\\\/12\\\/mercado-navideno-cordoba-2019\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mercado Navide\u00f1o C\u00f3rdoba 2019\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/#website\",\"url\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/\",\"name\":\"Apartamentos Plaza\",\"description\":\"Apartamentos Plaza en C\u00f3rdoba\",\"publisher\":{\"@id\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/#organization\",\"name\":\"Apartamentos tur\u00edsticos Plaza\",\"url\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i1.wp.com\\\/www.apartamentosplaza.com\\\/web\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/logo_plaza_fondo_blanco.png?fit=250%2C250&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i1.wp.com\\\/www.apartamentosplaza.com\\\/web\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/logo_plaza_fondo_blanco.png?fit=250%2C250&ssl=1\",\"width\":250,\"height\":250,\"caption\":\"Apartamentos tur\u00edsticos Plaza\"},\"image\":{\"@id\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/apartamentosplazacordoba\\\/\",\"https:\\\/\\\/www.instagram.com\\\/apartamentosplazacordoba\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/#\\\/schema\\\/person\\\/e29015ac64546f50bb06fb4f6921c2c2\",\"name\":\"apartamentosplaza\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/32ada2e22bc4563047e96fb2393977f0097c3adf658204a5562062b254b4a92b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/32ada2e22bc4563047e96fb2393977f0097c3adf658204a5562062b254b4a92b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/32ada2e22bc4563047e96fb2393977f0097c3adf658204a5562062b254b4a92b?s=96&d=mm&r=g\",\"caption\":\"apartamentosplaza\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mercado Navide\u00f1o C\u00f3rdoba 2019 - Apartamentos Plaza","description":"Este mes de noviembre se ha inciado el mercado navide\u00f1o de C\u00f3rdoba, \u00bfsabes donde est\u00e1, sus horarios y las novedades de este a\u00f1o? Apartamentos Plaza informa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/apartamentosplaza.com\/web\/index.php\/2019\/11\/12\/mercado-navideno-cordoba-2019\/","og_locale":"es_ES","og_type":"article","og_title":"Mercado Navide\u00f1o C\u00f3rdoba 2019 - Apartamentos Plaza","og_description":"Este mes de noviembre se ha inciado el mercado navide\u00f1o de C\u00f3rdoba, \u00bfsabes donde est\u00e1, sus horarios y las novedades de este a\u00f1o? Apartamentos Plaza informa","og_url":"https:\/\/apartamentosplaza.com\/web\/index.php\/2019\/11\/12\/mercado-navideno-cordoba-2019\/","og_site_name":"Apartamentos Plaza","article_publisher":"https:\/\/www.facebook.com\/apartamentosplazacordoba\/","article_published_time":"2019-11-12T17:53:57+00:00","article_modified_time":"2019-11-12T17:54:09+00:00","og_image":[{"width":545,"height":350,"url":"https:\/\/apartamentosplaza.com\/web\/wp-content\/uploads\/2019\/11\/mercado_navideno.jpg","type":"image\/jpeg"}],"author":"apartamentosplaza","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"apartamentosplaza","Tiempo de lectura":"16 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/apartamentosplaza.com\/web\/index.php\/2019\/11\/12\/mercado-navideno-cordoba-2019\/#article","isPartOf":{"@id":"https:\/\/apartamentosplaza.com\/web\/index.php\/2019\/11\/12\/mercado-navideno-cordoba-2019\/"},"author":{"name":"apartamentosplaza","@id":"https:\/\/apartamentosplaza.com\/web\/#\/schema\/person\/e29015ac64546f50bb06fb4f6921c2c2"},"headline":"Mercado Navide\u00f1o C\u00f3rdoba 2019","datePublished":"2019-11-12T17:53:57+00:00","dateModified":"2019-11-12T17:54:09+00:00","mainEntityOfPage":{"@id":"https:\/\/apartamentosplaza.com\/web\/index.php\/2019\/11\/12\/mercado-navideno-cordoba-2019\/"},"wordCount":3262,"commentCount":0,"publisher":{"@id":"https:\/\/apartamentosplaza.com\/web\/#organization"},"image":{"@id":"https:\/\/apartamentosplaza.com\/web\/index.php\/2019\/11\/12\/mercado-navideno-cordoba-2019\/#primaryimage"},"thumbnailUrl":"https:\/\/apartamentosplaza.com\/web\/wp-content\/uploads\/2019\/11\/mercado_navideno.jpg","keywords":["mercado","navidad"],"articleSection":["Eventos","Fiestas"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/apartamentosplaza.com\/web\/index.php\/2019\/11\/12\/mercado-navideno-cordoba-2019\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/apartamentosplaza.com\/web\/index.php\/2019\/11\/12\/mercado-navideno-cordoba-2019\/","url":"https:\/\/apartamentosplaza.com\/web\/index.php\/2019\/11\/12\/mercado-navideno-cordoba-2019\/","name":"Mercado Navide\u00f1o C\u00f3rdoba 2019 - Apartamentos Plaza","isPartOf":{"@id":"https:\/\/apartamentosplaza.com\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/apartamentosplaza.com\/web\/index.php\/2019\/11\/12\/mercado-navideno-cordoba-2019\/#primaryimage"},"image":{"@id":"https:\/\/apartamentosplaza.com\/web\/index.php\/2019\/11\/12\/mercado-navideno-cordoba-2019\/#primaryimage"},"thumbnailUrl":"https:\/\/apartamentosplaza.com\/web\/wp-content\/uploads\/2019\/11\/mercado_navideno.jpg","datePublished":"2019-11-12T17:53:57+00:00","dateModified":"2019-11-12T17:54:09+00:00","description":"Este mes de noviembre se ha inciado el mercado navide\u00f1o de C\u00f3rdoba, \u00bfsabes donde est\u00e1, sus horarios y las novedades de este a\u00f1o? Apartamentos Plaza informa","breadcrumb":{"@id":"https:\/\/apartamentosplaza.com\/web\/index.php\/2019\/11\/12\/mercado-navideno-cordoba-2019\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/apartamentosplaza.com\/web\/index.php\/2019\/11\/12\/mercado-navideno-cordoba-2019\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/apartamentosplaza.com\/web\/index.php\/2019\/11\/12\/mercado-navideno-cordoba-2019\/#primaryimage","url":"https:\/\/apartamentosplaza.com\/web\/wp-content\/uploads\/2019\/11\/mercado_navideno.jpg","contentUrl":"https:\/\/apartamentosplaza.com\/web\/wp-content\/uploads\/2019\/11\/mercado_navideno.jpg","width":545,"height":350},{"@type":"BreadcrumbList","@id":"https:\/\/apartamentosplaza.com\/web\/index.php\/2019\/11\/12\/mercado-navideno-cordoba-2019\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/apartamentosplaza.com\/web\/"},{"@type":"ListItem","position":2,"name":"Mercado Navide\u00f1o C\u00f3rdoba 2019"}]},{"@type":"WebSite","@id":"https:\/\/apartamentosplaza.com\/web\/#website","url":"https:\/\/apartamentosplaza.com\/web\/","name":"Apartamentos Plaza","description":"Apartamentos Plaza en C\u00f3rdoba","publisher":{"@id":"https:\/\/apartamentosplaza.com\/web\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/apartamentosplaza.com\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/apartamentosplaza.com\/web\/#organization","name":"Apartamentos tur\u00edsticos Plaza","url":"https:\/\/apartamentosplaza.com\/web\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/apartamentosplaza.com\/web\/#\/schema\/logo\/image\/","url":"https:\/\/i1.wp.com\/www.apartamentosplaza.com\/web\/wp-content\/uploads\/2018\/03\/logo_plaza_fondo_blanco.png?fit=250%2C250&ssl=1","contentUrl":"https:\/\/i1.wp.com\/www.apartamentosplaza.com\/web\/wp-content\/uploads\/2018\/03\/logo_plaza_fondo_blanco.png?fit=250%2C250&ssl=1","width":250,"height":250,"caption":"Apartamentos tur\u00edsticos Plaza"},"image":{"@id":"https:\/\/apartamentosplaza.com\/web\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/apartamentosplazacordoba\/","https:\/\/www.instagram.com\/apartamentosplazacordoba\/"]},{"@type":"Person","@id":"https:\/\/apartamentosplaza.com\/web\/#\/schema\/person\/e29015ac64546f50bb06fb4f6921c2c2","name":"apartamentosplaza","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/32ada2e22bc4563047e96fb2393977f0097c3adf658204a5562062b254b4a92b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/32ada2e22bc4563047e96fb2393977f0097c3adf658204a5562062b254b4a92b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/32ada2e22bc4563047e96fb2393977f0097c3adf658204a5562062b254b4a92b?s=96&d=mm&r=g","caption":"apartamentosplaza"}}]}},"jetpack_featured_media_url":"https:\/\/apartamentosplaza.com\/web\/wp-content\/uploads\/2019\/11\/mercado_navideno.jpg","_links":{"self":[{"href":"https:\/\/apartamentosplaza.com\/web\/index.php\/wp-json\/wp\/v2\/posts\/2048","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/apartamentosplaza.com\/web\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/apartamentosplaza.com\/web\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/apartamentosplaza.com\/web\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/apartamentosplaza.com\/web\/index.php\/wp-json\/wp\/v2\/comments?post=2048"}],"version-history":[{"count":3,"href":"https:\/\/apartamentosplaza.com\/web\/index.php\/wp-json\/wp\/v2\/posts\/2048\/revisions"}],"predecessor-version":[{"id":2062,"href":"https:\/\/apartamentosplaza.com\/web\/index.php\/wp-json\/wp\/v2\/posts\/2048\/revisions\/2062"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/apartamentosplaza.com\/web\/index.php\/wp-json\/wp\/v2\/media\/2052"}],"wp:attachment":[{"href":"https:\/\/apartamentosplaza.com\/web\/index.php\/wp-json\/wp\/v2\/media?parent=2048"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/apartamentosplaza.com\/web\/index.php\/wp-json\/wp\/v2\/categories?post=2048"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/apartamentosplaza.com\/web\/index.php\/wp-json\/wp\/v2\/tags?post=2048"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}