{"id":1973,"date":"2019-09-30T13:38:14","date_gmt":"2019-09-30T13:38:14","guid":{"rendered":"http:\/\/www.apartamentosplaza.com\/web\/?p=1973"},"modified":"2019-09-30T13:38:27","modified_gmt":"2019-09-30T13:38:27","slug":"sabias-que-la-calleja-de-las-flores","status":"publish","type":"post","link":"https:\/\/apartamentosplaza.com\/web\/index.php\/2019\/09\/30\/sabias-que-la-calleja-de-las-flores\/","title":{"rendered":"\u00bfSab\u00edas que&#8230; La calleja de las flores?"},"content":{"rendered":"\n[et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;About Us&#8221; _builder_version=&#8221;3.22.5&#8243; custom_padding=&#8221;0px||0px|||&#8221;][et_pb_row _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;0px||0px|||&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;3.22.5&#8243; custom_padding=&#8221;||0px|||&#8221;]\t\t<div id=\"sbi_mod_error\" >\n\t\t\t<span>This error message is only visible to WordPress admins<\/span><br\/>\n\t\t\t<p><strong>Error: No feed found.<\/strong>\n\t\t\t<p>Please go to the Instagram Feed settings page to create a feed.<\/p>\n\t\t<\/div>\n\t\t[\/et_pb_text][et_pb_social_media_follow _builder_version=&#8221;3.22.5&#8243;][et_pb_social_media_follow_network social_network=&#8221;facebook&#8221; url=&#8221;https:\/\/www.facebook.com\/Apartamentos-Plaza-1701558410070402\/&#8221; _builder_version=&#8221;3.22.5&#8243; background_color=&#8221;#3b5998&#8243; follow_button=&#8221;off&#8221; url_new_window=&#8221;on&#8221;]facebook[\/et_pb_social_media_follow_network][et_pb_social_media_follow_network social_network=&#8221;instagram&#8221; url=&#8221;https:\/\/www.instagram.com\/apartamentosplazacordoba\/&#8221; _builder_version=&#8221;3.22.5&#8243; background_color=&#8221;#ea2c59&#8243; follow_button=&#8221;off&#8221; url_new_window=&#8221;on&#8221;]instagram[\/et_pb_social_media_follow_network][\/et_pb_social_media_follow][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; next_background_color=&#8221;#000000&#8243; admin_label=&#8221;Header&#8221; _builder_version=&#8221;3.22.3&#8243; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_start=&#8221;rgba(0,37,68,0.7)&#8221; background_color_gradient_end=&#8221;rgba(0,37,68,0.5)&#8221; background_color_gradient_direction=&#8221;120deg&#8221; background_color_gradient_start_position=&#8221;60%&#8221; background_color_gradient_end_position=&#8221;60%&#8221; background_color_gradient_overlays_image=&#8221;on&#8221; background_image=&#8221;https:\/\/www.apartamentosplaza.com\/web\/wp-content\/uploads\/2019\/04\/soccer-11.jpg&#8221; custom_padding=&#8221;7vw|0px|7vw|0px|true|false&#8221; bottom_divider_style=&#8221;mountains2&#8243; bottom_divider_flip=&#8221;horizontal&#8221;][et_pb_row _builder_version=&#8221;3.25&#8243; custom_width_px=&#8221;1280px&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;3.16.1&#8243; text_font=&#8221;Open Sans||||||||&#8221; text_font_size=&#8221;16px&#8221; text_line_height=&#8221;1.8em&#8221; header_font=&#8221;Squada One|||on|||||&#8221; header_font_size=&#8221;60px&#8221; header_letter_spacing=&#8221;1px&#8221; header_line_height=&#8221;1.1em&#8221; background_layout=&#8221;dark&#8221; max_width=&#8221;700px&#8221; custom_padding=&#8221;||0px|||&#8221; animation_style=&#8221;fade&#8221; text_font_size_last_edited=&#8221;on|desktop&#8221; text_line_height_last_edited=&#8221;on|desktop&#8221; header_font_size_phone=&#8221;32px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221;]<h1>\u00bfSab\u00edas que&#8230;? la calleja de las flores<\/h1>\n<p class=\"m_-904313370925301319p1\" style=\"text-align: justify;\">Seguro que has escuchado hablar sobre la Calleja de las Flores, pero \u00bfconoces su historia y c\u00f3mo llegar hasta ella para visitarla? Te lo contamos en <a href=\"www.apartamentosplaza.com\">Apartamentos Plaza<\/a>.<\/p>\n<p class=\"m_-904313370925301319p1\"><span class=\"m_-904313370925301319s1\"><\/span><\/p>[\/et_pb_text][et_pb_video src=&#8221;https:\/\/www.youtube.com\/watch?v=EzN0CupkB24&#8243; _builder_version=&#8221;3.26.6&#8243; border_color_all=&#8221;#e09900&#8243; border_width_top=&#8221;8px&#8221; box_shadow_style=&#8221;preset1&#8243; box_shadow_vertical=&#8221;20px&#8221; box_shadow_blur=&#8221;80px&#8221; box_shadow_spread=&#8221;-20px&#8221; box_shadow_color=&#8221;#000000&#8243; custom_margin=&#8221;||0px&#8221;][\/et_pb_video][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Announcement&#8221; _builder_version=&#8221;3.22.3&#8243; background_color=&#8221;#000000&#8243; custom_padding=&#8221;10px||10px||true&#8221;][et_pb_row _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;0|0px|20px|0px|false|false&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;3.26.6&#8243; text_font=&#8221;||||||||&#8221; header_font=&#8221;||||||||&#8221; header_4_font=&#8221;Open Sans|700|||||||&#8221; header_4_font_size=&#8221;20px&#8221; header_4_line_height=&#8221;1.8em&#8221; background_layout=&#8221;dark&#8221; custom_margin=&#8221;||0px|&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;left&#8221; animation_intensity_slide=&#8221;10%&#8221; header_4_line_height_last_edited=&#8221;on|desktop&#8221; locked=&#8221;off&#8221;]<h4><span style=\"color: #00aaff;\">Fuente:<\/span> <a href=\"https:\/\/www.youtube.com\/channel\/UCY1-MIyiSidnRviSw6wzBdw\" target=\"_blank\" rel=\"noopener noreferrer\">Andaluc\u00eda Viajes<\/a><\/h4>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;About Us&#8221; _builder_version=&#8221;3.22.3&#8243; background_color=&#8221;#f4f4f4&#8243;][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;3.25&#8243; custom_margin=&#8221;|auto|-68px|auto||&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;3.26.6&#8243; text_font=&#8221;Open Sans||||||||&#8221; text_line_height=&#8221;1.8em&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;Squada One||||||||&#8221; header_2_font_size=&#8221;40px&#8221; border_color_all=&#8221;rgba(0,0,0,0)&#8221; border_width_top=&#8221;8px&#8221; custom_margin=&#8221;||0px|&#8221; custom_padding=&#8221;40px||40px||true|false&#8221; header_2_font_size_tablet=&#8221;35px&#8221; header_2_font_size_phone=&#8221;25px&#8221; header_2_font_size_last_edited=&#8221;on|desktop&#8221; max_width__hover=&#8221;100%&#8221; max_width__hover_enabled=&#8221;100%&#8221; use_background_color_gradient__hover=&#8221;off&#8221; use_background_color_gradient__hover_enabled=&#8221;off&#8221; background_color_gradient_start__hover=&#8221;#2b87da&#8221; background_color_gradient_start__hover_enabled=&#8221;#2b87da&#8221; background_color_gradient_end__hover=&#8221;#29c4a9&#8243; background_color_gradient_end__hover_enabled=&#8221;#29c4a9&#8243; background_color_gradient_type__hover=&#8221;linear&#8221; background_color_gradient_type__hover_enabled=&#8221;linear&#8221; background_color_gradient_direction__hover=&#8221;180deg&#8221; background_color_gradient_direction__hover_enabled=&#8221;180deg&#8221; background_color_gradient_direction_radial__hover=&#8221;center&#8221; background_color_gradient_direction_radial__hover_enabled=&#8221;center&#8221; background_color_gradient_start_position__hover=&#8221;0%&#8221; background_color_gradient_start_position__hover_enabled=&#8221;0%&#8221; background_color_gradient_end_position__hover=&#8221;100%&#8221; background_color_gradient_end_position__hover_enabled=&#8221;100%&#8221; background_color_gradient_overlays_image__hover=&#8221;off&#8221; background_color_gradient_overlays_image__hover_enabled=&#8221;off&#8221; parallax__hover=&#8221;off&#8221; parallax__hover_enabled=&#8221;off&#8221; parallax_method__hover=&#8221;on&#8221; parallax_method__hover_enabled=&#8221;on&#8221; background_size__hover=&#8221;cover&#8221; background_size__hover_enabled=&#8221;cover&#8221; background_position__hover=&#8221;center&#8221; background_position__hover_enabled=&#8221;center&#8221; background_repeat__hover=&#8221;no-repeat&#8221; background_repeat__hover_enabled=&#8221;no-repeat&#8221; background_blend__hover=&#8221;normal&#8221; background_blend__hover_enabled=&#8221;normal&#8221; allow_player_pause__hover=&#8221;off&#8221; allow_player_pause__hover_enabled=&#8221;off&#8221; background_video_pause_outside_viewport__hover=&#8221;on&#8221; background_video_pause_outside_viewport__hover_enabled=&#8221;on&#8221; box_shadow_style__hover=&#8221;none&#8221; box_shadow_style__hover_enabled=&#8221;none&#8221; box_shadow_color__hover=&#8221;rgba(0,0,0,0.3)&#8221; box_shadow_color__hover_enabled=&#8221;rgba(0,0,0,0.3)&#8221;]<h2>Su Historia<\/h2>\n<div class=\"page\" title=\"Page 1\">\n<div class=\"section\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p style=\"text-align: justify;\">\u00a0La plaza era en realidad un antiguo patio de vecinos t\u00edpico cordob\u00e9s, que con el devenir de los a\u00f1os se fue transformando en calle. Su aspecto actual se debe al inter\u00e9s por parte del alcalde Alfonso Cruz-Conde en embellecer determinados sitios de C\u00f3rdoba, entre los que se encontraba <span style=\"color: #e09900;\"><strong>la calleja de las Flores<\/strong><\/span>, aunque ser\u00eda su hermano Antonio Cruz-Conde, el que se encargar\u00eda de la ejecuci\u00f3n al alcanzar tambi\u00e9n la alcald\u00eda.<\/p>\n<p style=\"text-align: justify;\">El proyecto de remodelaci\u00f3n fue dise\u00f1ado a mediados de los a\u00f1os 1950 por el arquitecto V\u00edctor Escribano Ucelay, quien llev\u00f3 a cabo su ornamentaci\u00f3n con la construcci\u00f3n de los arquillos que hoy la contemplan, la transformaci\u00f3n del antiguo pavimento de losas de cemento por los t\u00edpicos cantos rodados, el emplazamiento de un capitel califal en la esquina al comienzo de la calleja y se orden\u00f3 que se decorara con macetas floridas.<\/p>\n<p style=\"text-align: justify;\">Adem\u00e1s, se preve\u00eda la construcci\u00f3n de una fuente de m\u00e1rmol, pero Enrique Romero de Torres, impulsor de la idea, disent\u00eda de que el material fue el m\u00e1s propicio para el entorno, por lo que fue Rafael Bernier Soldevilla, vecino de la misma calle y profesor de la escuela de artes, el que realizar\u00eda la actual fuente octogonal integrando restos arqueol\u00f3gicos como una columna romana en el a\u00f1o 1960. Desde entonces, la calleja de las Flores se ha convertido en un icono fotogr\u00e1fico de la ciudad siendo cientos los turistas que diariamente retratan la imagen de la torre de la Mezquita desde la peque\u00f1a plaza terminal de la calleja de las Flores<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"page\" title=\"Page 1\">\n<div class=\"section\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p style=\"text-align: justify;\"><span><\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p style=\"text-align: justify;\"><span>Si te est\u00e1 gustando visita nuestras <strong><a href=\"https:\/\/www.apartamentosplaza.com\/web\/index.php\/noticias\/\">noticias<\/a><\/strong>.<\/span><\/p>\n<p style=\"text-align: justify;\"><\/p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/www.apartamentosplaza.com\/web\/wp-content\/uploads\/2019\/09\/Konexion-Tours-Cordoba-Unica-Calle-de-las-Flores-02.jpg&#8221; align=&#8221;center&#8221; align_tablet=&#8221;center&#8221; align_last_edited=&#8221;on|desktop&#8221; _builder_version=&#8221;3.26.6&#8243; box_shadow_style=&#8221;preset2&#8243; box_shadow_horizontal=&#8221;23px&#8221; box_shadow_blur=&#8221;21px&#8221; custom_padding=&#8221;46px||1px|||&#8221;][\/et_pb_image][et_pb_image src=&#8221;https:\/\/www.apartamentosplaza.com\/web\/wp-content\/uploads\/2019\/09\/riojun-0004-velvia.jpg&#8221; _builder_version=&#8221;3.26.6&#8243;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;3.25&#8243;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;3.23.3&#8243; text_font=&#8221;Open Sans||||||||&#8221; text_text_align=&#8221;justify&#8221; text_line_height=&#8221;1.8em&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;Squada One||||||||&#8221; header_2_font_size=&#8221;40px&#8221; border_color_all=&#8221;rgba(0,0,0,0)&#8221; border_width_top=&#8221;8px&#8221; custom_margin=&#8221;||0px|&#8221; custom_padding=&#8221;27px||27px||true|false&#8221; header_2_font_size_tablet=&#8221;35px&#8221; header_2_font_size_phone=&#8221;25px&#8221; header_2_font_size_last_edited=&#8221;on|desktop&#8221; max_width__hover=&#8221;100%&#8221; max_width__hover_enabled=&#8221;100%&#8221; use_background_color_gradient__hover=&#8221;off&#8221; use_background_color_gradient__hover_enabled=&#8221;off&#8221; background_color_gradient_start__hover=&#8221;#2b87da&#8221; background_color_gradient_start__hover_enabled=&#8221;#2b87da&#8221; background_color_gradient_end__hover=&#8221;#29c4a9&#8243; background_color_gradient_end__hover_enabled=&#8221;#29c4a9&#8243; background_color_gradient_type__hover=&#8221;linear&#8221; background_color_gradient_type__hover_enabled=&#8221;linear&#8221; background_color_gradient_direction__hover=&#8221;180deg&#8221; background_color_gradient_direction__hover_enabled=&#8221;180deg&#8221; background_color_gradient_direction_radial__hover=&#8221;center&#8221; background_color_gradient_direction_radial__hover_enabled=&#8221;center&#8221; background_color_gradient_start_position__hover=&#8221;0%&#8221; background_color_gradient_start_position__hover_enabled=&#8221;0%&#8221; background_color_gradient_end_position__hover=&#8221;100%&#8221; background_color_gradient_end_position__hover_enabled=&#8221;100%&#8221; background_color_gradient_overlays_image__hover=&#8221;off&#8221; background_color_gradient_overlays_image__hover_enabled=&#8221;off&#8221; parallax__hover=&#8221;off&#8221; parallax__hover_enabled=&#8221;off&#8221; parallax_method__hover=&#8221;on&#8221; parallax_method__hover_enabled=&#8221;on&#8221; background_size__hover=&#8221;cover&#8221; background_size__hover_enabled=&#8221;cover&#8221; background_position__hover=&#8221;center&#8221; background_position__hover_enabled=&#8221;center&#8221; background_repeat__hover=&#8221;no-repeat&#8221; background_repeat__hover_enabled=&#8221;no-repeat&#8221; background_blend__hover=&#8221;normal&#8221; background_blend__hover_enabled=&#8221;normal&#8221; allow_player_pause__hover=&#8221;off&#8221; allow_player_pause__hover_enabled=&#8221;off&#8221; background_video_pause_outside_viewport__hover=&#8221;on&#8221; background_video_pause_outside_viewport__hover_enabled=&#8221;on&#8221; box_shadow_style__hover=&#8221;none&#8221; box_shadow_style__hover_enabled=&#8221;none&#8221; box_shadow_color__hover=&#8221;rgba(0,0,0,0.3)&#8221; box_shadow_color__hover_enabled=&#8221;rgba(0,0,0,0.3)&#8221;]<h2>\u00bfDonde est\u00e1?<span style=\"font-size: 14px; font-family: 'Open Sans', Helvetica, Arial, Lucida, sans-serif; color: #666666;\">\u00a0<\/span><\/h2>\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\"><\/div>\n<\/div>\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p><span>En pleno barrio de la\u00a0<\/span><strong>Juder\u00eda<\/strong><span>, cerca de la\u00a0<\/span><strong>Mezquita-Catedral de C\u00f3rdoba<\/strong><span>\u00a0encontramos esta apacible calleja, una de las\u00a0<\/span><strong>m\u00e1s tradicionales<\/strong><span>\u00a0de la ciudad. Estrechita y sinuosa,\u00a0sube en una suave pendiente hasta la\u00a0<\/span><strong>peque\u00f1a plazoleta<\/strong><span>\u00a0en la que desemboca. Los balcones enrejados se llenan de flores aromatizando el agradable paseo del visitante. Desde la\u00a0<\/span><strong>fuente<\/strong><span>\u00a0que centra la plazoleta podemos disfrutar de una de las m\u00e1s bellas vistas de la\u00a0<\/span><strong>torre de la Mezquita-Catedral<\/strong><span>.<\/span><\/p>\n<\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><\/p>[\/et_pb_text][et_pb_code _builder_version=&#8221;3.26.6&#8243; transform_scale_linked=&#8221;off&#8221; text_orientation=&#8221;center&#8221;]<iframe loading=\"lazy\" src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m18!1m12!1m3!1d3149.1387478258475!2d-4.7795454!3d37.880437799999996!2m3!1f0!2f0!3f0!3m2!1i1024!2i768!4f13.1!3m3!1m2!1s0xd6d209d4a954cb9%3A0xad030aa113c6d6b4!2sCalleja%20de%20las%20Flores%2C%2014003%20C%C3%B3rdoba!5e0!3m2!1ses!2ses!4v1569849748231!5m2!1ses!2ses\" width=\"600\" height=\"450\" frameborder=\"0\" style=\"border:0;\" allowfullscreen=\"\"><\/iframe>[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Gallery &#8221; _builder_version=&#8221;3.22.7&#8243; background_color=&#8221;#18252c&#8221; custom_margin=&#8221;0px||&#8221; custom_padding=&#8221;0px|0px|0px|0px|true|false&#8221;][et_pb_row column_structure=&#8221;1_2,1_2&#8243; use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;1&#8243; module_class=&#8221; et_pb_row_fullwidth&#8221; _builder_version=&#8221;3.25&#8243; width=&#8221;100%&#8221; width_tablet=&#8221;100%&#8221; width_last_edited=&#8221;on|desktop&#8221; max_width=&#8221;100%&#8221; max_width_tablet=&#8221;100%&#8221; max_width_last_edited=&#8221;on|desktop&#8221; custom_padding=&#8221;0|0px|0|0px|true|false&#8221; make_fullwidth=&#8221;on&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/www.apartamentosplaza.com\/web\/wp-content\/uploads\/2019\/09\/nuevo-hotel-ubicara-Flores-Encarnacion_1363674095_101313357_667x375.jpg&#8221; show_in_lightbox=&#8221;on&#8221; use_overlay=&#8221;on&#8221; overlay_icon_color=&#8221;#ffffff&#8221; hover_overlay_color=&#8221;rgba(255,255,255,0.1)&#8221; align_tablet=&#8221;center&#8221; align_last_edited=&#8221;on|desktop&#8221; _builder_version=&#8221;3.26.6&#8243; custom_margin=&#8221;|0px||&#8221; custom_margin_last_edited=&#8221;off|desktop&#8221; animation_style=&#8221;zoom&#8221; animation_intensity_zoom=&#8221;20%&#8221; custom_margin__hover=&#8221;|||&#8221; force_fullwidth=&#8221;on&#8221; height=&#8221;407px&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/www.apartamentosplaza.com\/web\/wp-content\/uploads\/2019\/09\/Cordoba-calle-flores-h4-ch.jpg&#8221; show_in_lightbox=&#8221;on&#8221; use_overlay=&#8221;on&#8221; overlay_icon_color=&#8221;#ffffff&#8221; hover_overlay_color=&#8221;rgba(255,255,255,0.1)&#8221; align_tablet=&#8221;center&#8221; align_last_edited=&#8221;on|desktop&#8221; _builder_version=&#8221;3.26.6&#8243; custom_margin=&#8221;||||false|false&#8221; custom_margin_tablet=&#8221;0px||&#8221; custom_margin_last_edited=&#8221;on|desktop&#8221; animation_style=&#8221;zoom&#8221; animation_intensity_zoom=&#8221;20%&#8221; locked=&#8221;off&#8221; custom_margin__hover_enabled=&#8221;on&#8221; custom_margin__hover=&#8221;-50px||&#8221; force_fullwidth=&#8221;on&#8221; height=&#8221;407px&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Programs&#8221; _builder_version=&#8221;3.22.3&#8243; background_color=&#8221;#18252c&#8221; custom_padding=&#8221;39px|0px|0|0px|false|false&#8221;][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Our Story&#8221; _builder_version=&#8221;3.22.7&#8243; background_color=&#8221;#f4f4f4&#8243; custom_margin=&#8221;-30px||&#8221; custom_padding=&#8221;27px||30px|||&#8221;][\/et_pb_section]\n","protected":false},"excerpt":{"rendered":"<p>La historia e informaci\u00f3n de la calleja de las flores de C\u00f3rdoba. Apartamentos Plaza te informa de este rinc\u00f3n de color y luz junto a la Mezquita de C\u00f3rdoba<\/p>\n","protected":false},"author":1,"featured_media":1975,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[53],"tags":[71,75],"class_list":["post-1973","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sabias-que","tag-historia","tag-sabias-que"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfSab\u00edas que... La calleja de las flores? - Apartamentos Plaza<\/title>\n<meta name=\"description\" content=\"La historia e informaci\u00f3n de la calleja de las flores de C\u00f3rdoba. Apartamentos Plaza te informa de este rinc\u00f3n de color y luz junto a la Mezquita de C\u00f3rdoba\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/apartamentosplaza.com\/web\/index.php\/2019\/09\/30\/sabias-que-la-calleja-de-las-flores\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfSab\u00edas que... La calleja de las flores? - Apartamentos Plaza\" \/>\n<meta property=\"og:description\" content=\"La historia e informaci\u00f3n de la calleja de las flores de C\u00f3rdoba. Apartamentos Plaza te informa de este rinc\u00f3n de color y luz junto a la Mezquita de C\u00f3rdoba\" \/>\n<meta property=\"og:url\" content=\"https:\/\/apartamentosplaza.com\/web\/index.php\/2019\/09\/30\/sabias-que-la-calleja-de-las-flores\/\" \/>\n<meta property=\"og:site_name\" content=\"Apartamentos Plaza\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/apartamentosplazacordoba\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-30T13:38:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-09-30T13:38:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/apartamentosplaza.com\/web\/wp-content\/uploads\/2019\/09\/Cordoba-calle-flores-h4-ch.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"745\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"apartamentosplaza\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"apartamentosplaza\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/index.php\\\/2019\\\/09\\\/30\\\/sabias-que-la-calleja-de-las-flores\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/index.php\\\/2019\\\/09\\\/30\\\/sabias-que-la-calleja-de-las-flores\\\/\"},\"author\":{\"name\":\"apartamentosplaza\",\"@id\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/#\\\/schema\\\/person\\\/e29015ac64546f50bb06fb4f6921c2c2\"},\"headline\":\"\u00bfSab\u00edas que&#8230; La calleja de las flores?\",\"datePublished\":\"2019-09-30T13:38:14+00:00\",\"dateModified\":\"2019-09-30T13:38:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/index.php\\\/2019\\\/09\\\/30\\\/sabias-que-la-calleja-de-las-flores\\\/\"},\"wordCount\":1934,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/index.php\\\/2019\\\/09\\\/30\\\/sabias-que-la-calleja-de-las-flores\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/Cordoba-calle-flores-h4-ch.jpg\",\"keywords\":[\"historia\",\"sabias que\"],\"articleSection\":[\"Sab\u00edas que.....\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/index.php\\\/2019\\\/09\\\/30\\\/sabias-que-la-calleja-de-las-flores\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/index.php\\\/2019\\\/09\\\/30\\\/sabias-que-la-calleja-de-las-flores\\\/\",\"url\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/index.php\\\/2019\\\/09\\\/30\\\/sabias-que-la-calleja-de-las-flores\\\/\",\"name\":\"\u00bfSab\u00edas que... La calleja de las flores? - Apartamentos Plaza\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/index.php\\\/2019\\\/09\\\/30\\\/sabias-que-la-calleja-de-las-flores\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/index.php\\\/2019\\\/09\\\/30\\\/sabias-que-la-calleja-de-las-flores\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/Cordoba-calle-flores-h4-ch.jpg\",\"datePublished\":\"2019-09-30T13:38:14+00:00\",\"dateModified\":\"2019-09-30T13:38:27+00:00\",\"description\":\"La historia e informaci\u00f3n de la calleja de las flores de C\u00f3rdoba. Apartamentos Plaza te informa de este rinc\u00f3n de color y luz junto a la Mezquita de C\u00f3rdoba\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/index.php\\\/2019\\\/09\\\/30\\\/sabias-que-la-calleja-de-las-flores\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/index.php\\\/2019\\\/09\\\/30\\\/sabias-que-la-calleja-de-las-flores\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/index.php\\\/2019\\\/09\\\/30\\\/sabias-que-la-calleja-de-las-flores\\\/#primaryimage\",\"url\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/Cordoba-calle-flores-h4-ch.jpg\",\"contentUrl\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/Cordoba-calle-flores-h4-ch.jpg\",\"width\":1000,\"height\":745},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/index.php\\\/2019\\\/09\\\/30\\\/sabias-que-la-calleja-de-las-flores\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfSab\u00edas que&#8230; La calleja de las flores?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/#website\",\"url\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/\",\"name\":\"Apartamentos Plaza\",\"description\":\"Apartamentos Plaza en C\u00f3rdoba\",\"publisher\":{\"@id\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/#organization\",\"name\":\"Apartamentos tur\u00edsticos Plaza\",\"url\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i1.wp.com\\\/www.apartamentosplaza.com\\\/web\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/logo_plaza_fondo_blanco.png?fit=250%2C250&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i1.wp.com\\\/www.apartamentosplaza.com\\\/web\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/logo_plaza_fondo_blanco.png?fit=250%2C250&ssl=1\",\"width\":250,\"height\":250,\"caption\":\"Apartamentos tur\u00edsticos Plaza\"},\"image\":{\"@id\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/apartamentosplazacordoba\\\/\",\"https:\\\/\\\/www.instagram.com\\\/apartamentosplazacordoba\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/#\\\/schema\\\/person\\\/e29015ac64546f50bb06fb4f6921c2c2\",\"name\":\"apartamentosplaza\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/32ada2e22bc4563047e96fb2393977f0097c3adf658204a5562062b254b4a92b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/32ada2e22bc4563047e96fb2393977f0097c3adf658204a5562062b254b4a92b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/32ada2e22bc4563047e96fb2393977f0097c3adf658204a5562062b254b4a92b?s=96&d=mm&r=g\",\"caption\":\"apartamentosplaza\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfSab\u00edas que... La calleja de las flores? - Apartamentos Plaza","description":"La historia e informaci\u00f3n de la calleja de las flores de C\u00f3rdoba. Apartamentos Plaza te informa de este rinc\u00f3n de color y luz junto a la Mezquita de C\u00f3rdoba","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/apartamentosplaza.com\/web\/index.php\/2019\/09\/30\/sabias-que-la-calleja-de-las-flores\/","og_locale":"en_US","og_type":"article","og_title":"\u00bfSab\u00edas que... La calleja de las flores? - Apartamentos Plaza","og_description":"La historia e informaci\u00f3n de la calleja de las flores de C\u00f3rdoba. Apartamentos Plaza te informa de este rinc\u00f3n de color y luz junto a la Mezquita de C\u00f3rdoba","og_url":"https:\/\/apartamentosplaza.com\/web\/index.php\/2019\/09\/30\/sabias-que-la-calleja-de-las-flores\/","og_site_name":"Apartamentos Plaza","article_publisher":"https:\/\/www.facebook.com\/apartamentosplazacordoba\/","article_published_time":"2019-09-30T13:38:14+00:00","article_modified_time":"2019-09-30T13:38:27+00:00","og_image":[{"width":1000,"height":745,"url":"https:\/\/apartamentosplaza.com\/web\/wp-content\/uploads\/2019\/09\/Cordoba-calle-flores-h4-ch.jpg","type":"image\/jpeg"}],"author":"apartamentosplaza","twitter_card":"summary_large_image","twitter_misc":{"Written by":"apartamentosplaza","Est. reading time":"10 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/apartamentosplaza.com\/web\/index.php\/2019\/09\/30\/sabias-que-la-calleja-de-las-flores\/#article","isPartOf":{"@id":"https:\/\/apartamentosplaza.com\/web\/index.php\/2019\/09\/30\/sabias-que-la-calleja-de-las-flores\/"},"author":{"name":"apartamentosplaza","@id":"https:\/\/apartamentosplaza.com\/web\/#\/schema\/person\/e29015ac64546f50bb06fb4f6921c2c2"},"headline":"\u00bfSab\u00edas que&#8230; La calleja de las flores?","datePublished":"2019-09-30T13:38:14+00:00","dateModified":"2019-09-30T13:38:27+00:00","mainEntityOfPage":{"@id":"https:\/\/apartamentosplaza.com\/web\/index.php\/2019\/09\/30\/sabias-que-la-calleja-de-las-flores\/"},"wordCount":1934,"commentCount":0,"publisher":{"@id":"https:\/\/apartamentosplaza.com\/web\/#organization"},"image":{"@id":"https:\/\/apartamentosplaza.com\/web\/index.php\/2019\/09\/30\/sabias-que-la-calleja-de-las-flores\/#primaryimage"},"thumbnailUrl":"https:\/\/apartamentosplaza.com\/web\/wp-content\/uploads\/2019\/09\/Cordoba-calle-flores-h4-ch.jpg","keywords":["historia","sabias que"],"articleSection":["Sab\u00edas que....."],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/apartamentosplaza.com\/web\/index.php\/2019\/09\/30\/sabias-que-la-calleja-de-las-flores\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/apartamentosplaza.com\/web\/index.php\/2019\/09\/30\/sabias-que-la-calleja-de-las-flores\/","url":"https:\/\/apartamentosplaza.com\/web\/index.php\/2019\/09\/30\/sabias-que-la-calleja-de-las-flores\/","name":"\u00bfSab\u00edas que... La calleja de las flores? - Apartamentos Plaza","isPartOf":{"@id":"https:\/\/apartamentosplaza.com\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/apartamentosplaza.com\/web\/index.php\/2019\/09\/30\/sabias-que-la-calleja-de-las-flores\/#primaryimage"},"image":{"@id":"https:\/\/apartamentosplaza.com\/web\/index.php\/2019\/09\/30\/sabias-que-la-calleja-de-las-flores\/#primaryimage"},"thumbnailUrl":"https:\/\/apartamentosplaza.com\/web\/wp-content\/uploads\/2019\/09\/Cordoba-calle-flores-h4-ch.jpg","datePublished":"2019-09-30T13:38:14+00:00","dateModified":"2019-09-30T13:38:27+00:00","description":"La historia e informaci\u00f3n de la calleja de las flores de C\u00f3rdoba. Apartamentos Plaza te informa de este rinc\u00f3n de color y luz junto a la Mezquita de C\u00f3rdoba","breadcrumb":{"@id":"https:\/\/apartamentosplaza.com\/web\/index.php\/2019\/09\/30\/sabias-que-la-calleja-de-las-flores\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/apartamentosplaza.com\/web\/index.php\/2019\/09\/30\/sabias-que-la-calleja-de-las-flores\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/apartamentosplaza.com\/web\/index.php\/2019\/09\/30\/sabias-que-la-calleja-de-las-flores\/#primaryimage","url":"https:\/\/apartamentosplaza.com\/web\/wp-content\/uploads\/2019\/09\/Cordoba-calle-flores-h4-ch.jpg","contentUrl":"https:\/\/apartamentosplaza.com\/web\/wp-content\/uploads\/2019\/09\/Cordoba-calle-flores-h4-ch.jpg","width":1000,"height":745},{"@type":"BreadcrumbList","@id":"https:\/\/apartamentosplaza.com\/web\/index.php\/2019\/09\/30\/sabias-que-la-calleja-de-las-flores\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/apartamentosplaza.com\/web\/"},{"@type":"ListItem","position":2,"name":"\u00bfSab\u00edas que&#8230; La calleja de las flores?"}]},{"@type":"WebSite","@id":"https:\/\/apartamentosplaza.com\/web\/#website","url":"https:\/\/apartamentosplaza.com\/web\/","name":"Apartamentos Plaza","description":"Apartamentos Plaza en C\u00f3rdoba","publisher":{"@id":"https:\/\/apartamentosplaza.com\/web\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/apartamentosplaza.com\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/apartamentosplaza.com\/web\/#organization","name":"Apartamentos tur\u00edsticos Plaza","url":"https:\/\/apartamentosplaza.com\/web\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/apartamentosplaza.com\/web\/#\/schema\/logo\/image\/","url":"https:\/\/i1.wp.com\/www.apartamentosplaza.com\/web\/wp-content\/uploads\/2018\/03\/logo_plaza_fondo_blanco.png?fit=250%2C250&ssl=1","contentUrl":"https:\/\/i1.wp.com\/www.apartamentosplaza.com\/web\/wp-content\/uploads\/2018\/03\/logo_plaza_fondo_blanco.png?fit=250%2C250&ssl=1","width":250,"height":250,"caption":"Apartamentos tur\u00edsticos Plaza"},"image":{"@id":"https:\/\/apartamentosplaza.com\/web\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/apartamentosplazacordoba\/","https:\/\/www.instagram.com\/apartamentosplazacordoba\/"]},{"@type":"Person","@id":"https:\/\/apartamentosplaza.com\/web\/#\/schema\/person\/e29015ac64546f50bb06fb4f6921c2c2","name":"apartamentosplaza","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/32ada2e22bc4563047e96fb2393977f0097c3adf658204a5562062b254b4a92b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/32ada2e22bc4563047e96fb2393977f0097c3adf658204a5562062b254b4a92b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/32ada2e22bc4563047e96fb2393977f0097c3adf658204a5562062b254b4a92b?s=96&d=mm&r=g","caption":"apartamentosplaza"}}]}},"jetpack_featured_media_url":"https:\/\/apartamentosplaza.com\/web\/wp-content\/uploads\/2019\/09\/Cordoba-calle-flores-h4-ch.jpg","_links":{"self":[{"href":"https:\/\/apartamentosplaza.com\/web\/index.php\/wp-json\/wp\/v2\/posts\/1973","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/apartamentosplaza.com\/web\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/apartamentosplaza.com\/web\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/apartamentosplaza.com\/web\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/apartamentosplaza.com\/web\/index.php\/wp-json\/wp\/v2\/comments?post=1973"}],"version-history":[{"count":7,"href":"https:\/\/apartamentosplaza.com\/web\/index.php\/wp-json\/wp\/v2\/posts\/1973\/revisions"}],"predecessor-version":[{"id":1988,"href":"https:\/\/apartamentosplaza.com\/web\/index.php\/wp-json\/wp\/v2\/posts\/1973\/revisions\/1988"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/apartamentosplaza.com\/web\/index.php\/wp-json\/wp\/v2\/media\/1975"}],"wp:attachment":[{"href":"https:\/\/apartamentosplaza.com\/web\/index.php\/wp-json\/wp\/v2\/media?parent=1973"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/apartamentosplaza.com\/web\/index.php\/wp-json\/wp\/v2\/categories?post=1973"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/apartamentosplaza.com\/web\/index.php\/wp-json\/wp\/v2\/tags?post=1973"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}