{"id":1828,"date":"2019-07-18T10:38:26","date_gmt":"2019-07-18T10:38:26","guid":{"rendered":"http:\/\/www.apartamentosplaza.com\/web\/?p=1828"},"modified":"2019-07-18T10:38:35","modified_gmt":"2019-07-18T10:38:35","slug":"visitar-cordoba-playas","status":"publish","type":"post","link":"https:\/\/apartamentosplaza.com\/web\/index.php\/2019\/07\/18\/visitar-cordoba-playas\/","title":{"rendered":"Visita C\u00f3rdoba: Playas para visitar"},"content":{"rendered":"\n[et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbAbout Us\u00bb _builder_version=\u00bb3.22.5&#8243; custom_padding=\u00bb0px||0px|||\u00bb][et_pb_row custom_padding=\u00bb0px||0px|||\u00bb _builder_version=\u00bb3.25&#8243;][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb3.25&#8243; custom_padding=\u00bb|||\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text _builder_version=\u00bb3.22.5&#8243; custom_padding=\u00bb||0px|||\u00bb]\t\t<div id=\"sbi_mod_error\" >\n\t\t\t<span>Este mensaje de error solo es visible para los administradores de WordPress<\/span><br\/>\n\t\t\t<p><strong>Error: No se ha encontrado ning\u00fan feed.<\/strong>\n\t\t\t<p>Por favor, ve a la p\u00e1gina de ajustes de Instagram Feed para crear un feed.<\/p>\n\t\t<\/div>\n\t\t[\/et_pb_text][et_pb_social_media_follow _builder_version=\u00bb3.22.5&#8243;][et_pb_social_media_follow_network social_network=\u00bbfacebook\u00bb url=\u00bbhttps:\/\/www.facebook.com\/Apartamentos-Plaza-1701558410070402\/\u00bb _builder_version=\u00bb3.22.5&#8243; background_color=\u00bb#3b5998&#8243; follow_button=\u00bboff\u00bb url_new_window=\u00bbon\u00bb]facebook[\/et_pb_social_media_follow_network][et_pb_social_media_follow_network social_network=\u00bbinstagram\u00bb url=\u00bbhttps:\/\/www.instagram.com\/apartamentosplazacordoba\/\u00bb _builder_version=\u00bb3.22.5&#8243; background_color=\u00bb#ea2c59&#8243; follow_button=\u00bboff\u00bb url_new_window=\u00bbon\u00bb]instagram[\/et_pb_social_media_follow_network][\/et_pb_social_media_follow][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; next_background_color=\u00bb#000000&#8243; admin_label=\u00bbHeader\u00bb _builder_version=\u00bb3.22.3&#8243; use_background_color_gradient=\u00bbon\u00bb background_color_gradient_start=\u00bbrgba(0,37,68,0.7)\u00bb background_color_gradient_end=\u00bbrgba(0,37,68,0.5)\u00bb background_color_gradient_direction=\u00bb120deg\u00bb background_color_gradient_start_position=\u00bb60%\u00bb background_color_gradient_end_position=\u00bb60%\u00bb background_color_gradient_overlays_image=\u00bbon\u00bb background_image=\u00bbhttps:\/\/www.apartamentosplaza.com\/web\/wp-content\/uploads\/2019\/04\/soccer-11.jpg\u00bb custom_padding=\u00bb7vw|0px|7vw|0px|true|false\u00bb bottom_divider_style=\u00bbmountains2&#8243; bottom_divider_flip=\u00bbhorizontal\u00bb][et_pb_row _builder_version=\u00bb3.25&#8243; custom_width_px=\u00bb1280px\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb3.25&#8243; custom_padding=\u00bb|||\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text _builder_version=\u00bb3.16.1&#8243; text_font=\u00bbOpen Sans||||||||\u00bb text_font_size=\u00bb16px\u00bb text_line_height=\u00bb1.8em\u00bb header_font=\u00bbSquada One|||on|||||\u00bb header_font_size=\u00bb60px\u00bb header_letter_spacing=\u00bb1px\u00bb header_line_height=\u00bb1.1em\u00bb background_layout=\u00bbdark\u00bb max_width=\u00bb700px\u00bb custom_padding=\u00bb||0px|||\u00bb animation_style=\u00bbfade\u00bb text_font_size_last_edited=\u00bbon|desktop\u00bb text_line_height_last_edited=\u00bbon|desktop\u00bb header_font_size_phone=\u00bb32px\u00bb header_font_size_last_edited=\u00bbon|phone\u00bb]<h1>visita c\u00f3rdoba y sus playas m\u00e1s cercanas<\/h1>\n<p class=\"m_-904313370925301319p1\" style=\"text-align: justify;\">Como sabr\u00e1s C\u00f3rdoba es una provincia muy extensa de interior de la comunidad de Andaluc\u00eda, al sur de Espa\u00f1a, pero no dispone de zona costera. \u00bfPero crees que esto es un problema para poder ba\u00f1arse cerca de la ciudad, en una playa? Ya te digo que no, lee a continuaci\u00f3n y te explicamos todas las zonas de playa que se pueden\u00a0disfrutar en C\u00f3rdoba desde 15 minutos de camino desde el centro de la ciudad y desde nuestros\u00a0<a href=\"https:\/\/www.apartamentosplaza.com\/web\">Apartamentos Plaza<\/a> de C\u00f3rdoba<\/p>\n<p><span class=\"m_-904313370925301319s1\"><\/span><\/p>\n<p class=\"m_-904313370925301319p1\"><span class=\"m_-904313370925301319s1\"><\/span><\/p>[\/et_pb_text][et_pb_video src=\u00bbhttps:\/\/www.youtube.com\/watch?v=03DnlSu_Nf4&#8243; _builder_version=\u00bb3.26.3&#8243; border_color_all=\u00bb#e09900&#8243; border_width_top=\u00bb8px\u00bb box_shadow_style=\u00bbpreset1&#8243; box_shadow_vertical=\u00bb20px\u00bb box_shadow_blur=\u00bb80px\u00bb box_shadow_spread=\u00bb-20px\u00bb box_shadow_color=\u00bb#000000&#8243; custom_margin=\u00bb||0px\u00bb][\/et_pb_video][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbAnnouncement\u00bb _builder_version=\u00bb3.22.3&#8243; background_color=\u00bb#000000&#8243; custom_padding=\u00bb10px||10px||true\u00bb][et_pb_row custom_padding=\u00bb0|0px|20px|0px|false|false\u00bb _builder_version=\u00bb3.25&#8243;][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb3.25&#8243; custom_padding=\u00bb|||\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text _builder_version=\u00bb3.16.1&#8243; text_font=\u00bb||||||||\u00bb header_font=\u00bb||||||||\u00bb header_4_font=\u00bbOpen Sans|700|||||||\u00bb header_4_font_size=\u00bb20px\u00bb header_4_line_height=\u00bb1.8em\u00bb background_layout=\u00bbdark\u00bb custom_margin=\u00bb||0px|\u00bb animation_style=\u00bbslide\u00bb animation_direction=\u00bbleft\u00bb animation_intensity_slide=\u00bb10%\u00bb header_4_line_height_last_edited=\u00bbon|desktop\u00bb locked=\u00bboff\u00bb]<h4><span style=\"color: #00aaff;\">Fuente:<\/span> <a href=\"https:\/\/www.artencordoba.com\/\">Andaluc\u00eda directo y Ayuntamiento de Izn\u00e1jar<\/a><\/h4>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbAbout Us\u00bb _builder_version=\u00bb3.22.3&#8243; background_color=\u00bb#f4f4f4&#8243;][et_pb_row _builder_version=\u00bb3.25&#8243;][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb3.25&#8243; custom_padding=\u00bb|||\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text _builder_version=\u00bb3.26.3&#8243; text_font=\u00bbOpen Sans||||||||\u00bb text_text_align=\u00bbjustify\u00bb text_line_height=\u00bb1.8em\u00bb header_font=\u00bb||||||||\u00bb header_2_font=\u00bbSquada One||||||||\u00bb header_2_font_size=\u00bb40px\u00bb border_color_all=\u00bbrgba(0,0,0,0)\u00bb border_width_top=\u00bb8px\u00bb custom_margin=\u00bb||0px|\u00bb custom_padding=\u00bb40px||40px||true|false\u00bb header_2_font_size_tablet=\u00bb35px\u00bb header_2_font_size_phone=\u00bb25px\u00bb header_2_font_size_last_edited=\u00bbon|desktop\u00bb max_width__hover=\u00bb100%\u00bb max_width__hover_enabled=\u00bb100%\u00bb use_background_color_gradient__hover=\u00bboff\u00bb use_background_color_gradient__hover_enabled=\u00bboff\u00bb background_color_gradient_start__hover=\u00bb#2b87da\u00bb background_color_gradient_start__hover_enabled=\u00bb#2b87da\u00bb background_color_gradient_end__hover=\u00bb#29c4a9&#8243; background_color_gradient_end__hover_enabled=\u00bb#29c4a9&#8243; background_color_gradient_type__hover=\u00bblinear\u00bb background_color_gradient_type__hover_enabled=\u00bblinear\u00bb background_color_gradient_direction__hover=\u00bb180deg\u00bb background_color_gradient_direction__hover_enabled=\u00bb180deg\u00bb background_color_gradient_direction_radial__hover=\u00bbcenter\u00bb background_color_gradient_direction_radial__hover_enabled=\u00bbcenter\u00bb background_color_gradient_start_position__hover=\u00bb0%\u00bb background_color_gradient_start_position__hover_enabled=\u00bb0%\u00bb background_color_gradient_end_position__hover=\u00bb100%\u00bb background_color_gradient_end_position__hover_enabled=\u00bb100%\u00bb background_color_gradient_overlays_image__hover=\u00bboff\u00bb background_color_gradient_overlays_image__hover_enabled=\u00bboff\u00bb parallax__hover=\u00bboff\u00bb parallax__hover_enabled=\u00bboff\u00bb parallax_method__hover=\u00bbon\u00bb parallax_method__hover_enabled=\u00bbon\u00bb background_size__hover=\u00bbcover\u00bb background_size__hover_enabled=\u00bbcover\u00bb background_position__hover=\u00bbcenter\u00bb background_position__hover_enabled=\u00bbcenter\u00bb background_repeat__hover=\u00bbno-repeat\u00bb background_repeat__hover_enabled=\u00bbno-repeat\u00bb background_blend__hover=\u00bbnormal\u00bb background_blend__hover_enabled=\u00bbnormal\u00bb allow_player_pause__hover=\u00bboff\u00bb allow_player_pause__hover_enabled=\u00bboff\u00bb background_video_pause_outside_viewport__hover=\u00bbon\u00bb background_video_pause_outside_viewport__hover_enabled=\u00bbon\u00bb box_shadow_style__hover=\u00bbnone\u00bb box_shadow_style__hover_enabled=\u00bbnone\u00bb box_shadow_color__hover=\u00bbrgba(0,0,0,0.3)\u00bb box_shadow_color__hover_enabled=\u00bbrgba(0,0,0,0.3)\u00bb]<h2>Playas de C\u00f3rdoba. \u00bfCuales son, y como llegar hasta ellas?<span style=\"font-size: 14px; font-family: 'Open Sans', Helvetica, Arial, Lucida, sans-serif; color: #666666;\">\u00a0<\/span><\/h2>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><span>Con la llegada del verano se hace presente la necesidad de <\/span><strong class=\"mce\">combatir el calor<\/strong><span> por el que es conocida C\u00f3rdoba. Por suerte para sus habitantes y turistas, a la oferta de piscina municipales de toda la provincia se suman <\/span><strong class=\"mce\">tres playas de interior<\/strong><span> -situadas en Almod\u00f3var, el Viso e Izn\u00e1jar- pueblos muy\u00a0cercanos y de f\u00e1cil acceso desde la ciudad, que hacen posible que los cordobeses tengan una orilla con sombrilla y chiringuito en su propia tierra.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3 style=\"text-align: justify;\"><strong>Playa en Almod\u00f3var del R\u00edo<\/strong><span style=\"font-size: 14px;\">\u00a0<\/span><\/h3>\n<p class=\"mce\">En pleno <strong class=\"mce\">Valle del Guadalquivir<\/strong>, y a poco m\u00e1s de 20 kil\u00f3metros de la capital, media hora en coche, se ubica la playa de <strong class=\"mce\">La Bre\u00f1a<\/strong>, que el <strong class=\"mce\">Ayuntamiento de Almod\u00f3var del R\u00edo<\/strong> <a href=\"https:\/\/www.eldiadecordoba.es\/provincia\/embalse-Brena-cuenta-primera-Cordoba_0_1253874936.html\" class=\"mce\">ya abri\u00f3 en 2018.<\/a><\/p>\n<p><span style=\"font-size: 14px;\">La zona de ba\u00f1o, de 140 metros de longitud, se ubica en el paraje conocido como <\/span><strong style=\"font-size: 14px;\">El Pinillo<\/strong><span style=\"font-size: 14px;\">, junto al chiringuito y el \u00e1rea de actividades recreativas, donde tambi\u00e9n se ha habilitado una zona de estacionamiento.<\/span><span style=\"font-size: 14px;\">\u00a0<\/span><span style=\"font-size: 14px;\">\u00a0<\/span><\/p>\n<p class=\"mce\">En el verano de este a\u00f1o, el Ayuntamiento carbulense <strong class=\"mce\">ampliar\u00e1 las zonas de ba\u00f1o habilitadas<\/strong>, que en 2018 ocupaban un arenal de unos 150 metros de extensi\u00f3n, aunque realmente est\u00e1 permitido darse un chapuz\u00f3n en cualquier punto debido a que la calidad del agua es apta. Tambi\u00e9n habr\u00e1 m\u00e1s sombrillas y se mejorar\u00e1n los accesos, informan fuentes municipales. La temporada de ba\u00f1o arrancar\u00e1 oficialmente el 15 de junio y se prolongar\u00e1 hasta el 30 de septiembre, fechas en las que habr\u00e1 servicio de socorrista.<\/p>\n<p class=\"mce\"><span>Para acceder a la la Bre\u00f1a, en <\/span><a href=\"https:\/\/www.eldiadecordoba.es\/tag\/almodovar_del_rio\/\" class=\"mce\">Almod\u00f3var del R\u00edo<\/a><span>, es necesario tomar<\/span><strong class=\"mce\"> la carretera A-431<\/strong><span> desde la capital y conducir hasta la localidad. Una vez all\u00ed,\u00a0<\/span><span>es necesario continuar el camino que lleva <\/span><strong class=\"mce\">hasta el embalse<\/strong><span>, mayormente por carretera excepto uno de los tramos cercanos a la zona de ba\u00f1o, la cual cuenta con una zona de aparcamiento adaptada cerca de la playa.<\/span><\/p>\n<p class=\"mce\">Si prefieres hacer uso de la tecnolog\u00eda pulsa <a href=\"https:\/\/goo.gl\/maps\/bFnURbYiWapzmiG1A\">aqu\u00ed<\/a> para poder obtener las indicaciones de navegaci\u00f3n por gps para llegar al destino.<\/p>\n<p>&nbsp;<\/p>\n<h3 style=\"text-align: justify;\"><strong>Playa en el Viso<\/strong><\/h3>\n<p><span>Se trata de una playa que estar\u00e1 ubicada a dos kil\u00f3metros del par\u00e1metro de la presa, ocupando una superficie total de 1.780 metros cuadrados y una longitud de 125 metros. Para tenerlo todo a punto, el Ayuntamiento ha acondicionado la zona para mantener en todo momento todas las condiciones de limpieza, higiene y salubridad en el entorno de la playa. Para ello, adem\u00e1s, se han acondicionado contenedores para residuos, preparado todas las medidas de seguridad pertinentes y apostado por el cuidado del medio ambiente con la instalaci\u00f3n de unas farolas que funcionan gracias a unos paneles solares.<\/span><\/p>\n<p><span>La zona recreativa de <span style=\"color: #e09900;\">La Colada<\/span>, que ya acoge todo tipo de actividades a lo largo de todo el a\u00f1o, se convertir\u00e1 desde ma\u00f1ana en un lugar de ba\u00f1o adaptado a todos los p\u00fablicos. Un nuevo elemento que sumar a la extensa oferta de turismo interior con la que cuenta la comarca de Los Pedroches, ofreciendo al turista una experiencia \u00fanica, viviendo la posibilidad de combatir el calor con un ba\u00f1o mientras se encuentra rodeado de encinas.<\/span><span style=\"font-size: 14px;\">\u00a0<\/span><\/p>\n<p><span>En el caso de la Colada, en <a href=\"https:\/\/www.eldiadecordoba.es\/tag\/el_viso\/\" class=\"mce\">El Viso<\/a>, se trata de un viaje m\u00e1s largo ( <strong class=\"mce\">1 hora y 15 minutos<\/strong>) que, desde la capital, se inicia por la <strong class=\"mce\">N-432<\/strong>. Un vez alcanzado el municipio de Espiel, es necesario tomar la carretera <strong class=\"mce\">N-502<\/strong> hasta llegar a el Viso. La playa se encuentra pasando la localidad, y cuenta con un aparcamiento adaptado.<\/span><span style=\"font-size: 14px;\">\u00a0<\/span><\/p>\n<p><span>Si prefieres hacer uso de la tecnolog\u00eda pulsa <a href=\"https:\/\/goo.gl\/maps\/wSjPVyekM8Y1uiq56\">aqu\u00ed<\/a> para poder obtener las indicaciones de navegaci\u00f3n por gps para llegar al destino.<\/span><\/p>\n<p><span style=\"font-size: 14px;\">\u00a0<\/span><\/p>\n<h3 style=\"text-align: justify;\"><strong>Playa en Izn\u00e1jar<\/strong><span style=\"font-size: 14px;\">\u00a0<\/span><span style=\"font-size: 14px;\">\u00a0<\/span><\/h3>\n<p style=\"text-align: justify;\">En todo caso, en la playa de Valdearenas ya est\u00e1n preparadas las sombrillas y los hidropedales aguardan en la orilla a que, oficialmente, arranque la temporada de ba\u00f1o. Como el propio alcalde admite, son ya muchas las personas que desde que empez\u00f3 el buen tiempo se acercan a este enclave para tomar el sol y darse un chapuz\u00f3n. En <span style=\"color: #e09900;\">Valdearenas<\/span>, adem\u00e1s, se practican la pesca y los deportes acu\u00e1ticos como el kayak. La oferta la completa una terraza bar con gran arboleda y desde la que se divisan las aguas azules del pantano.<span style=\"font-size: 14px;\">\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span>Por \u00faltimo, en <\/span><a href=\"https:\/\/www.eldiadecordoba.es\/tag\/iznajar\/\" class=\"mce\">Izn\u00e1jar<\/a><span>\u00a0se encuentra la playa de Valdearenas, a un distancia similar que la Colada. Para llegar a ella es necesario tomar la <\/span><strong class=\"mce\">A-45<\/strong><span> hasta tomar el desv\u00edo en Encinas Reales a la A-334 y a la <\/span><strong class=\"mce\">A-331 en Rute<\/strong><span>. Siguiendo esta carretera y tomando <\/span><strong class=\"mce\">direcci\u00f3n al camping<\/strong><span>, se accede al aparcamiento de la zona de ba\u00f1o.<\/span><\/p>\n<p style=\"text-align: justify;\"><span>Si prefieres hacer uso de la tecnolog\u00eda pulsa <a href=\"https:\/\/goo.gl\/maps\/BbXsMzmnoSXsbKcu5\">aqu\u00ed<\/a> para poder obtener las indicaciones de navegaci\u00f3n por gps para llegar al destino.<\/span><span style=\"font-size: 14px;\">\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span><\/span><\/p>\n<h3 style=\"text-align: justify;\"><span><\/span><\/h3>\n<h3 style=\"text-align: justify;\"><span><\/span><strong>Playas de costa<\/strong><\/h3>\n<p style=\"text-align: justify;\">Si por el contrario eres m\u00e1s de la playa de toda la vida, con vistas al mar, te proponemos las playas de costa m\u00e1s cercanas de la ciudad.<span style=\"font-size: 14px;\">\u00a0<\/span><span style=\"font-size: 14px;\">\u00a0<\/span><\/p>\n<p>El listado de <strong>playas de M\u00e1laga <\/strong>que destacan por ser las <strong>mejores\u00a0<\/strong>este verano son las siguientes:<span style=\"font-size: 14px;\">\u00a0<\/span><\/p>\n<p><strong>\u2022Torrox<\/strong>: Ferrera.<\/p>\n<p><strong>\u2022Algarrobo<\/strong>: Algarrobo Costa.<\/p>\n<p><strong>\u2022V\u00e9lez-M\u00e1laga<\/strong>: Benajarafe, Torre del Mar y La Caleta Paseo.<\/p>\n<p><strong>\u2022Benalm\u00e1dena<\/strong>: Fuente de la Salud y Torrebermeja-Santa Ana.<span style=\"font-size: 14px;\">\u00a0<\/span><\/p>\n<p><strong>\u2022Mijas<\/strong>: La Cala-Torre\u00f3n; El Bombo y Calahonda I (Royal Beach-La Luna).<span style=\"font-size: 14px;\">\u00a0<\/span><\/p>\n<p><strong>\u2022Fuengirola<\/strong>: Carvajal.<\/p>\n<p><strong>\u2022Marbella<\/strong>: Casablanca, El Faro y San Pedro de Alc\u00e1ntara (Guadalmina).<span style=\"font-size: 14px;\">\u00a0<\/span><\/p>\n<p><strong>\u2022Estepona<\/strong>: El Cristo y Arroyo Vaquero.<span style=\"font-size: 14px;\">\u00a0<\/span><span style=\"font-size: 14px;\">\u00a0<\/span><\/p>\n<p>\u2022<strong>Casares<\/strong>: Ancha<\/p>\n<p>&nbsp;<\/p>\n<p>A quienes no les importe conducir una hora m\u00e1s hasta la provincia de\u00a0<strong>C\u00e1diz<\/strong> no se sentir\u00e1n defraudados. Este a\u00f1o, <strong>29 de sus playas han obtenido banderas azules<\/strong>. Sancti Petri, en Chiclana, La Muralla, en El Puerto de Santa Mar\u00eda y Alcaidesa, en San Roque, han logrado consolidar la distinci\u00f3n.<span style=\"font-size: 14px;\">\u00a0<\/span><\/p>\n<p>A estas playas se suman La Barrosa (Chiclana); Los Bateles, Roche y La Fontanilla (Conil); La Puntilla, Las Redes, Fuentebrav\u00eda y Valdelagrana (El Puerto); Cortadura, La Victoria, La Caleta y Santa Mar\u00eda del Mar (C\u00e1diz); Camposoto (San Fernando); Galeones, Rompidillo-Chorrillo, Puntalillo, La Costilla, Punta Candor y La Ballena (Rota); Camar\u00f3n-La Laguna, Regla, Cruz del Mar-Las Canteras y Micaela (Chipiona); Getares (Algeciras) y Torreguadiaro y Cala Sardina (San Roque).<\/p>\n<p style=\"text-align: justify;\">[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbGallery \u00bb _builder_version=\u00bb3.22.7&#8243; background_color=\u00bb#18252c\u00bb custom_margin=\u00bb0px||\u00bb custom_padding=\u00bb0px|0px|0px|0px|true|false\u00bb][et_pb_row column_structure=\u00bb1_4,1_4,1_2&#8243; use_custom_gutter=\u00bbon\u00bb gutter_width=\u00bb1&#8243; custom_padding=\u00bb0|0px|0|0px|true|false\u00bb module_class=\u00bb et_pb_row_fullwidth\u00bb _builder_version=\u00bb3.25&#8243; width=\u00bb100%\u00bb width_tablet=\u00bb100%\u00bb width_last_edited=\u00bbon|desktop\u00bb max_width=\u00bb100%\u00bb max_width_tablet=\u00bb100%\u00bb max_width_last_edited=\u00bbon|desktop\u00bb make_fullwidth=\u00bbon\u00bb][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb3.25&#8243; custom_padding=\u00bb|||\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_image src=\u00bbhttps:\/\/www.apartamentosplaza.com\/web\/wp-content\/uploads\/2019\/07\/valdearrenas-playa-preview-kPpD-620&#215;349@abc.jpg\u00bb show_in_lightbox=\u00bbon\u00bb use_overlay=\u00bbon\u00bb overlay_icon_color=\u00bb#ffffff\u00bb hover_overlay_color=\u00bbrgba(255,255,255,0.1)\u00bb align_tablet=\u00bbcenter\u00bb align_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb3.26.3&#8243; custom_margin=\u00bb|0px||\u00bb custom_margin_last_edited=\u00bboff|desktop\u00bb animation_style=\u00bbzoom\u00bb animation_intensity_zoom=\u00bb20%\u00bb custom_margin__hover=\u00bb|||\u00bb][\/et_pb_image][et_pb_image src=\u00bbhttps:\/\/www.apartamentosplaza.com\/web\/wp-content\/uploads\/2019\/07\/playas-rios-cordoba.jpg\u00bb show_in_lightbox=\u00bbon\u00bb use_overlay=\u00bbon\u00bb overlay_icon_color=\u00bb#ffffff\u00bb hover_overlay_color=\u00bbrgba(255,255,255,0.1)\u00bb force_fullwidth=\u00bbon\u00bb align_tablet=\u00bbcenter\u00bb align_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb3.26.3&#8243; box_shadow_style=\u00bbpreset1&#8243; box_shadow_vertical=\u00bb0px\u00bb box_shadow_blur=\u00bb100px\u00bb box_shadow_spread=\u00bb50px\u00bb box_shadow_color=\u00bbrgba(0,0,0,0.8)\u00bb max_width_tablet=\u00bb100%\u00bb max_width_last_edited=\u00bbon|tablet\u00bb module_alignment=\u00bbright\u00bb custom_margin=\u00bb-10px||\u00bb custom_margin_tablet=\u00bb0px||\u00bb custom_margin_last_edited=\u00bbon|desktop\u00bb animation_style=\u00bbzoom\u00bb animation_intensity_zoom=\u00bb20%\u00bb locked=\u00bboff\u00bb custom_margin__hover_enabled=\u00bbon\u00bb custom_margin__hover=\u00bb-20px||\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb3.25&#8243; custom_padding=\u00bb|||\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_image src=\u00bbhttps:\/\/www.apartamentosplaza.com\/web\/wp-content\/uploads\/2019\/07\/1241875_1.jpg\u00bb show_in_lightbox=\u00bbon\u00bb use_overlay=\u00bbon\u00bb overlay_icon_color=\u00bb#ffffff\u00bb hover_overlay_color=\u00bbrgba(255,255,255,0.1)\u00bb align_tablet=\u00bbcenter\u00bb align_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb3.26.3&#8243; custom_margin=\u00bb-40px||\u00bb custom_margin_tablet=\u00bb0px||\u00bb custom_margin_last_edited=\u00bbon|desktop\u00bb animation_style=\u00bbzoom\u00bb animation_intensity_zoom=\u00bb20%\u00bb locked=\u00bboff\u00bb custom_margin__hover_enabled=\u00bbon\u00bb custom_margin__hover=\u00bb-50px||\u00bb][\/et_pb_image][et_pb_image src=\u00bbhttps:\/\/www.apartamentosplaza.com\/web\/wp-content\/uploads\/2019\/07\/2018071816403685671.jpg\u00bb show_in_lightbox=\u00bbon\u00bb use_overlay=\u00bbon\u00bb overlay_icon_color=\u00bb#ffffff\u00bb hover_overlay_color=\u00bbrgba(255,255,255,0.1)\u00bb align_tablet=\u00bbcenter\u00bb align_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb3.26.3&#8243; box_shadow_style=\u00bbpreset1&#8243; box_shadow_vertical=\u00bb0px\u00bb box_shadow_blur=\u00bb100px\u00bb box_shadow_spread=\u00bb50px\u00bb box_shadow_color=\u00bbrgba(0,0,0,0.8)\u00bb custom_margin=\u00bb|||\u00bb custom_margin_tablet=\u00bb0px|||0px\u00bb custom_margin_last_edited=\u00bbon|desktop\u00bb animation_style=\u00bbzoom\u00bb animation_intensity_zoom=\u00bb20%\u00bb locked=\u00bboff\u00bb custom_margin__hover_enabled=\u00bbon\u00bb custom_margin__hover=\u00bb-20px|||\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb3.25&#8243; custom_padding=\u00bb|||\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_image src=\u00bbhttps:\/\/www.apartamentosplaza.com\/web\/wp-content\/uploads\/2019\/07\/DiaES13WAAAXzys.jpg\u00bb show_in_lightbox=\u00bbon\u00bb use_overlay=\u00bbon\u00bb overlay_icon_color=\u00bb#ffffff\u00bb hover_overlay_color=\u00bbrgba(255,255,255,0.1)\u00bb force_fullwidth=\u00bbon\u00bb align_tablet=\u00bbcenter\u00bb align_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb3.26.3&#8243; box_shadow_style=\u00bbpreset1&#8243; box_shadow_vertical=\u00bb0px\u00bb box_shadow_blur=\u00bb100px\u00bb box_shadow_spread=\u00bb50px\u00bb box_shadow_color=\u00bbrgba(0,0,0,0.8)\u00bb max_height=\u00bb434px\u00bb custom_margin=\u00bb-80px||\u00bb custom_margin_tablet=\u00bb0px||\u00bb custom_margin_last_edited=\u00bbon|desktop\u00bb animation_style=\u00bbzoom\u00bb animation_intensity_zoom=\u00bb20%\u00bb locked=\u00bboff\u00bb custom_margin__hover_enabled=\u00bbon\u00bb custom_margin__hover=\u00bb|||-20px\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbPrograms\u00bb _builder_version=\u00bb3.22.3&#8243; background_color=\u00bb#18252c\u00bb custom_padding=\u00bb39px|0px|0|0px|false|false\u00bb][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbOur Story\u00bb _builder_version=\u00bb3.22.7&#8243; background_color=\u00bb#f4f4f4&#8243; custom_margin=\u00bb-30px||\u00bb custom_padding=\u00bb27px||30px|||\u00bb][\/et_pb_section]\n","protected":false},"excerpt":{"rendered":"<p>Todas las claves para disfrutar de las playas cercanas de costa y de interior de la provincia de C\u00f3rdoba. Apartamentos Plaza te informa<\/p>\n","protected":false},"author":1,"featured_media":1834,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[68,25],"tags":[66,67],"class_list":["post-1828","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-lugares","category-viajar","tag-playas","tag-sitiosparavisitar"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Visita C\u00f3rdoba: Playas para visitar - Apartamentos Plaza<\/title>\n<meta name=\"description\" content=\"Todas las claves para disfrutar de las playas cercanas de costa y de interior de la provincia de C\u00f3rdoba. Apartamentos Plaza te informa\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/apartamentosplaza.com\/web\/index.php\/2019\/07\/18\/visitar-cordoba-playas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Visita C\u00f3rdoba: Playas para visitar - Apartamentos Plaza\" \/>\n<meta property=\"og:description\" content=\"Todas las claves para disfrutar de las playas cercanas de costa y de interior de la provincia de C\u00f3rdoba. Apartamentos Plaza te informa\" \/>\n<meta property=\"og:url\" content=\"https:\/\/apartamentosplaza.com\/web\/index.php\/2019\/07\/18\/visitar-cordoba-playas\/\" \/>\n<meta property=\"og:site_name\" content=\"Apartamentos Plaza\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/apartamentosplazacordoba\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-18T10:38:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-07-18T10:38:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/apartamentosplaza.com\/web\/wp-content\/uploads\/2019\/07\/valdearrenas-playa-preview-kPpD-620x349@abc.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"618\" \/>\n\t<meta property=\"og:image:height\" content=\"349\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"apartamentosplaza\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"apartamentosplaza\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"13 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/index.php\\\/2019\\\/07\\\/18\\\/visitar-cordoba-playas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/index.php\\\/2019\\\/07\\\/18\\\/visitar-cordoba-playas\\\/\"},\"author\":{\"name\":\"apartamentosplaza\",\"@id\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/#\\\/schema\\\/person\\\/e29015ac64546f50bb06fb4f6921c2c2\"},\"headline\":\"Visita C\u00f3rdoba: Playas para visitar\",\"datePublished\":\"2019-07-18T10:38:26+00:00\",\"dateModified\":\"2019-07-18T10:38:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/index.php\\\/2019\\\/07\\\/18\\\/visitar-cordoba-playas\\\/\"},\"wordCount\":2567,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/index.php\\\/2019\\\/07\\\/18\\\/visitar-cordoba-playas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/valdearrenas-playa-preview-kPpD-620x349@abc.jpg\",\"keywords\":[\"Playas\",\"sitiosparavisitar\"],\"articleSection\":[\"Lugares\",\"Viajar\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/index.php\\\/2019\\\/07\\\/18\\\/visitar-cordoba-playas\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/index.php\\\/2019\\\/07\\\/18\\\/visitar-cordoba-playas\\\/\",\"url\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/index.php\\\/2019\\\/07\\\/18\\\/visitar-cordoba-playas\\\/\",\"name\":\"Visita C\u00f3rdoba: Playas para visitar - Apartamentos Plaza\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/index.php\\\/2019\\\/07\\\/18\\\/visitar-cordoba-playas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/index.php\\\/2019\\\/07\\\/18\\\/visitar-cordoba-playas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/valdearrenas-playa-preview-kPpD-620x349@abc.jpg\",\"datePublished\":\"2019-07-18T10:38:26+00:00\",\"dateModified\":\"2019-07-18T10:38:35+00:00\",\"description\":\"Todas las claves para disfrutar de las playas cercanas de costa y de interior de la provincia de C\u00f3rdoba. Apartamentos Plaza te informa\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/index.php\\\/2019\\\/07\\\/18\\\/visitar-cordoba-playas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/index.php\\\/2019\\\/07\\\/18\\\/visitar-cordoba-playas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/index.php\\\/2019\\\/07\\\/18\\\/visitar-cordoba-playas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/valdearrenas-playa-preview-kPpD-620x349@abc.jpg\",\"contentUrl\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/valdearrenas-playa-preview-kPpD-620x349@abc.jpg\",\"width\":618,\"height\":349,\"caption\":\"Playa vadearrenas\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/index.php\\\/2019\\\/07\\\/18\\\/visitar-cordoba-playas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Visita C\u00f3rdoba: Playas para visitar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/#website\",\"url\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/\",\"name\":\"Apartamentos Plaza\",\"description\":\"Apartamentos Plaza en C\u00f3rdoba\",\"publisher\":{\"@id\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/#organization\",\"name\":\"Apartamentos tur\u00edsticos Plaza\",\"url\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i1.wp.com\\\/www.apartamentosplaza.com\\\/web\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/logo_plaza_fondo_blanco.png?fit=250%2C250&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i1.wp.com\\\/www.apartamentosplaza.com\\\/web\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/logo_plaza_fondo_blanco.png?fit=250%2C250&ssl=1\",\"width\":250,\"height\":250,\"caption\":\"Apartamentos tur\u00edsticos Plaza\"},\"image\":{\"@id\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/apartamentosplazacordoba\\\/\",\"https:\\\/\\\/www.instagram.com\\\/apartamentosplazacordoba\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/#\\\/schema\\\/person\\\/e29015ac64546f50bb06fb4f6921c2c2\",\"name\":\"apartamentosplaza\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/32ada2e22bc4563047e96fb2393977f0097c3adf658204a5562062b254b4a92b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/32ada2e22bc4563047e96fb2393977f0097c3adf658204a5562062b254b4a92b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/32ada2e22bc4563047e96fb2393977f0097c3adf658204a5562062b254b4a92b?s=96&d=mm&r=g\",\"caption\":\"apartamentosplaza\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Visita C\u00f3rdoba: Playas para visitar - Apartamentos Plaza","description":"Todas las claves para disfrutar de las playas cercanas de costa y de interior de la provincia de C\u00f3rdoba. Apartamentos Plaza te informa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/apartamentosplaza.com\/web\/index.php\/2019\/07\/18\/visitar-cordoba-playas\/","og_locale":"es_ES","og_type":"article","og_title":"Visita C\u00f3rdoba: Playas para visitar - Apartamentos Plaza","og_description":"Todas las claves para disfrutar de las playas cercanas de costa y de interior de la provincia de C\u00f3rdoba. Apartamentos Plaza te informa","og_url":"https:\/\/apartamentosplaza.com\/web\/index.php\/2019\/07\/18\/visitar-cordoba-playas\/","og_site_name":"Apartamentos Plaza","article_publisher":"https:\/\/www.facebook.com\/apartamentosplazacordoba\/","article_published_time":"2019-07-18T10:38:26+00:00","article_modified_time":"2019-07-18T10:38:35+00:00","og_image":[{"width":618,"height":349,"url":"https:\/\/apartamentosplaza.com\/web\/wp-content\/uploads\/2019\/07\/valdearrenas-playa-preview-kPpD-620x349@abc.jpg","type":"image\/jpeg"}],"author":"apartamentosplaza","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"apartamentosplaza","Tiempo de lectura":"13 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/apartamentosplaza.com\/web\/index.php\/2019\/07\/18\/visitar-cordoba-playas\/#article","isPartOf":{"@id":"https:\/\/apartamentosplaza.com\/web\/index.php\/2019\/07\/18\/visitar-cordoba-playas\/"},"author":{"name":"apartamentosplaza","@id":"https:\/\/apartamentosplaza.com\/web\/#\/schema\/person\/e29015ac64546f50bb06fb4f6921c2c2"},"headline":"Visita C\u00f3rdoba: Playas para visitar","datePublished":"2019-07-18T10:38:26+00:00","dateModified":"2019-07-18T10:38:35+00:00","mainEntityOfPage":{"@id":"https:\/\/apartamentosplaza.com\/web\/index.php\/2019\/07\/18\/visitar-cordoba-playas\/"},"wordCount":2567,"commentCount":0,"publisher":{"@id":"https:\/\/apartamentosplaza.com\/web\/#organization"},"image":{"@id":"https:\/\/apartamentosplaza.com\/web\/index.php\/2019\/07\/18\/visitar-cordoba-playas\/#primaryimage"},"thumbnailUrl":"https:\/\/apartamentosplaza.com\/web\/wp-content\/uploads\/2019\/07\/valdearrenas-playa-preview-kPpD-620x349@abc.jpg","keywords":["Playas","sitiosparavisitar"],"articleSection":["Lugares","Viajar"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/apartamentosplaza.com\/web\/index.php\/2019\/07\/18\/visitar-cordoba-playas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/apartamentosplaza.com\/web\/index.php\/2019\/07\/18\/visitar-cordoba-playas\/","url":"https:\/\/apartamentosplaza.com\/web\/index.php\/2019\/07\/18\/visitar-cordoba-playas\/","name":"Visita C\u00f3rdoba: Playas para visitar - Apartamentos Plaza","isPartOf":{"@id":"https:\/\/apartamentosplaza.com\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/apartamentosplaza.com\/web\/index.php\/2019\/07\/18\/visitar-cordoba-playas\/#primaryimage"},"image":{"@id":"https:\/\/apartamentosplaza.com\/web\/index.php\/2019\/07\/18\/visitar-cordoba-playas\/#primaryimage"},"thumbnailUrl":"https:\/\/apartamentosplaza.com\/web\/wp-content\/uploads\/2019\/07\/valdearrenas-playa-preview-kPpD-620x349@abc.jpg","datePublished":"2019-07-18T10:38:26+00:00","dateModified":"2019-07-18T10:38:35+00:00","description":"Todas las claves para disfrutar de las playas cercanas de costa y de interior de la provincia de C\u00f3rdoba. Apartamentos Plaza te informa","breadcrumb":{"@id":"https:\/\/apartamentosplaza.com\/web\/index.php\/2019\/07\/18\/visitar-cordoba-playas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/apartamentosplaza.com\/web\/index.php\/2019\/07\/18\/visitar-cordoba-playas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/apartamentosplaza.com\/web\/index.php\/2019\/07\/18\/visitar-cordoba-playas\/#primaryimage","url":"https:\/\/apartamentosplaza.com\/web\/wp-content\/uploads\/2019\/07\/valdearrenas-playa-preview-kPpD-620x349@abc.jpg","contentUrl":"https:\/\/apartamentosplaza.com\/web\/wp-content\/uploads\/2019\/07\/valdearrenas-playa-preview-kPpD-620x349@abc.jpg","width":618,"height":349,"caption":"Playa vadearrenas"},{"@type":"BreadcrumbList","@id":"https:\/\/apartamentosplaza.com\/web\/index.php\/2019\/07\/18\/visitar-cordoba-playas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/apartamentosplaza.com\/web\/"},{"@type":"ListItem","position":2,"name":"Visita C\u00f3rdoba: Playas para visitar"}]},{"@type":"WebSite","@id":"https:\/\/apartamentosplaza.com\/web\/#website","url":"https:\/\/apartamentosplaza.com\/web\/","name":"Apartamentos Plaza","description":"Apartamentos Plaza en C\u00f3rdoba","publisher":{"@id":"https:\/\/apartamentosplaza.com\/web\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/apartamentosplaza.com\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/apartamentosplaza.com\/web\/#organization","name":"Apartamentos tur\u00edsticos Plaza","url":"https:\/\/apartamentosplaza.com\/web\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/apartamentosplaza.com\/web\/#\/schema\/logo\/image\/","url":"https:\/\/i1.wp.com\/www.apartamentosplaza.com\/web\/wp-content\/uploads\/2018\/03\/logo_plaza_fondo_blanco.png?fit=250%2C250&ssl=1","contentUrl":"https:\/\/i1.wp.com\/www.apartamentosplaza.com\/web\/wp-content\/uploads\/2018\/03\/logo_plaza_fondo_blanco.png?fit=250%2C250&ssl=1","width":250,"height":250,"caption":"Apartamentos tur\u00edsticos Plaza"},"image":{"@id":"https:\/\/apartamentosplaza.com\/web\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/apartamentosplazacordoba\/","https:\/\/www.instagram.com\/apartamentosplazacordoba\/"]},{"@type":"Person","@id":"https:\/\/apartamentosplaza.com\/web\/#\/schema\/person\/e29015ac64546f50bb06fb4f6921c2c2","name":"apartamentosplaza","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/32ada2e22bc4563047e96fb2393977f0097c3adf658204a5562062b254b4a92b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/32ada2e22bc4563047e96fb2393977f0097c3adf658204a5562062b254b4a92b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/32ada2e22bc4563047e96fb2393977f0097c3adf658204a5562062b254b4a92b?s=96&d=mm&r=g","caption":"apartamentosplaza"}}]}},"jetpack_featured_media_url":"https:\/\/apartamentosplaza.com\/web\/wp-content\/uploads\/2019\/07\/valdearrenas-playa-preview-kPpD-620x349@abc.jpg","_links":{"self":[{"href":"https:\/\/apartamentosplaza.com\/web\/index.php\/wp-json\/wp\/v2\/posts\/1828","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/apartamentosplaza.com\/web\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/apartamentosplaza.com\/web\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/apartamentosplaza.com\/web\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/apartamentosplaza.com\/web\/index.php\/wp-json\/wp\/v2\/comments?post=1828"}],"version-history":[{"count":8,"href":"https:\/\/apartamentosplaza.com\/web\/index.php\/wp-json\/wp\/v2\/posts\/1828\/revisions"}],"predecessor-version":[{"id":1854,"href":"https:\/\/apartamentosplaza.com\/web\/index.php\/wp-json\/wp\/v2\/posts\/1828\/revisions\/1854"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/apartamentosplaza.com\/web\/index.php\/wp-json\/wp\/v2\/media\/1834"}],"wp:attachment":[{"href":"https:\/\/apartamentosplaza.com\/web\/index.php\/wp-json\/wp\/v2\/media?parent=1828"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/apartamentosplaza.com\/web\/index.php\/wp-json\/wp\/v2\/categories?post=1828"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/apartamentosplaza.com\/web\/index.php\/wp-json\/wp\/v2\/tags?post=1828"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}