{"id":647,"date":"2018-04-24T19:19:23","date_gmt":"2018-04-24T19:19:23","guid":{"rendered":"http:\/\/www.apartamentosplaza.com\/web\/?page_id=647"},"modified":"2018-04-24T19:19:23","modified_gmt":"2018-04-24T19:19:23","slug":"politica-de-cookies","status":"publish","type":"page","link":"https:\/\/apartamentosplaza.com\/web\/index.php\/politica-de-cookies\/","title":{"rendered":"Pol\u00edtica de Cookies"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;3.0.47&#8243;][et_pb_row _builder_version=&#8221;3.0.47&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;3.0.100&#8243; parallax=&#8221;off&#8221; parallax_method=&#8221;on&#8221;][et_pb_post_title meta=&#8221;off&#8221; featured_image=&#8221;off&#8221; _builder_version=&#8221;3.0.100&#8243; text_orientation=&#8221;center&#8221; title_font=&#8221;|||on|||||&#8221; title_font_size=&#8221;50px&#8221;][\/et_pb_post_title][et_pb_text _builder_version=&#8221;3.0.100&#8243;]<\/p>\n<div class=\"fusion-title title fusion-title-center fusion-title-size-one\">\n<h1 class=\"title-heading-center\" data-fontsize=\"34\" data-lineheight=\"47\"><\/h1>\n<\/div>\n<p><span>Cookie es un fichero que se descarga en su ordenador al acceder a determinadas p\u00e1ginas web. Las cookies permiten a una p\u00e1gina web, entre otras cosas, almacenar y recuperar informaci\u00f3n sobre los h\u00e1bitos de navegaci\u00f3n de un usuario o de su equipo y, dependiendo de la informaci\u00f3n que contengan y de la forma en que utilice su equipo, pueden utilizarse para reconocer al usuario. El navegador del usuario memoriza cookies en el disco duro solamente durante la sesi\u00f3n actual ocupando un espacio de memoria m\u00ednimo y no perjudicando al ordenador. Las cookies no contienen ninguna clase de informaci\u00f3n personal espec\u00edfica, y la mayor\u00eda de las mismas se borran del disco duro al finalizar la sesi\u00f3n de navegador (las denominadas cookies de sesi\u00f3n).<\/span><\/p>\n<p><span>La mayor\u00eda de los navegadores aceptan como est\u00e1ndar a las cookies y, con independencia de las mismas, permiten o impiden en los ajustes de seguridad las cookies temporales o memorizadas.<\/span><\/p>\n<p><span>Sin su expreso consentimiento \u2013mediante la activaci\u00f3n de las cookies en su navegador\u2013 APARTAMENTOS PLAZA. no enlazar\u00e1 en las cookies los datos memorizados con sus datos personales proporcionados en el momento del registro o la compra.<\/span><\/p>\n<p><strong><span>\u00bfQu\u00e9 tipos de cookies utiliza esta p\u00e1gina web?<\/span><\/strong><\/p>\n<p><span>Cookies t\u00e9cnicas: Son aqu\u00e9llas que permiten al usuario la navegaci\u00f3n a trav\u00e9s de una p\u00e1gina web, plataforma o aplicaci\u00f3n y la utilizaci\u00f3n de las diferentes opciones o servicios que en ella existan como, por ejemplo, controlar el tr\u00e1fico y la comunicaci\u00f3n de datos, identificar la sesi\u00f3n, acceder a partes de acceso restringido, recordar los elementos que integran un pedido, realizar el proceso de compra de un pedido, realizar la solicitud de inscripci\u00f3n o participaci\u00f3n en un evento, utilizar elementos de seguridad durante la navegaci\u00f3n, almacenar contenidos para la difusi\u00f3n de videos o sonido o compartir contenidos a trav\u00e9s de redes sociales.<\/span><\/p>\n<p><span>Cookies de personalizaci\u00f3n: Son aqu\u00e9llas que permiten al usuario acceder al servicio con algunas caracter\u00edsticas de car\u00e1cter general predefinidas en funci\u00f3n de una serie de criterios en el terminal del usuario como por ejemplo serian el idioma, el tipo de navegador a trav\u00e9s del cual accede al servicio, la configuraci\u00f3n regional desde donde accede al servicio, etc.<\/span><\/p>\n<p><span>Cookies de an\u00e1lisis: Son aqu\u00e9llas que bien tratadas por nosotros o por terceros, nos permiten cuantificar el n\u00famero de usuarios y as\u00ed realizar la medici\u00f3n y an\u00e1lisis estad\u00edstico de la utilizaci\u00f3n que hacen los usuarios del servicio ofertado. Para ello se analiza su navegaci\u00f3n en nuestra p\u00e1gina web con el fin de mejorar la oferta de productos o servicios que le ofrecemos.<\/span><\/p>\n<p><strong><span>Cookies de terceros<\/span><\/strong><\/p>\n<p><span>La Web de APARTAMENTOS PLAZA.. puede utilizar servicios de terceros que, por cuenta de APARTAMENTOS PLAZA., recopilaran informaci\u00f3n con fines estad\u00edsticos, de uso del Site por parte del usuario y para la prestacion de otros servicios relacionados con la actividad del Website y otros servicios de Internet.<\/span><\/p>\n<p><span>En particular, este sitio Web utiliza Google Analytics, un servicio anal\u00edtico de web prestado por Google, Inc. con domicilio en los Estados Unidos con sede central en 1600 Amphitheatre Parkway, Mountain View, California 94043. Para la prestaci\u00f3n de estos servicios, estos utilizan cookies que recopilan la informaci\u00f3n, incluida la direcci\u00f3n IP del usuario, que ser\u00e1 transmitida, tratada y almacenada por Google en los t\u00e9rminos fijados en la Web Google.com. Incluyendo la posible transmisi\u00f3n de dicha informaci\u00f3n a terceros por razones de exigencia legal o cuando dichos terceros procesen la informaci\u00f3n por cuenta de Google.<\/span><\/p>\n<p><span>El Usuario acepta expresamente, por la utilizaci\u00f3n de este Site, el tratamiento de la informaci\u00f3n recabada en la forma y con los fines anteriormente mencionados. Y asimismo reconoce conocer la posibilidad de rechazar el tratamiento de tales datos o informaci\u00f3n rechazando el uso de Cookies mediante la selecci\u00f3n de la configuraci\u00f3n apropiada a tal fin en su navegador. Si bien esta opci\u00f3n de bloqueo de Cookies en su navegador puede no permitirle el uso pleno de todas las funcionalidades del Website.<\/span><\/p>\n<p><span>Puede usted permitir, bloquear o eliminar las cookies instaladas en su equipo mediante la configuraci\u00f3n de las opciones del navegador instalado en su ordenador:<\/span><\/p>\n<p><span><a href=\"http:\/\/support.google.com\/chrome\/bin\/answer.py?hl=es&amp;answer=95647\">Chrome<\/a><\/span><br \/><span><a href=\"http:\/\/windows.microsoft.com\/es-es\/windows7\/how-to-manage-cookies-in-internet-explorer-9\">Explorer<\/a><\/span><br \/><span><a href=\"http:\/\/support.mozilla.org\/es\/kb\/habilitar-y-deshabilitar-cookies-que-los-sitios-we\">Firefox<\/a><\/span><br \/><span><a href=\"http:\/\/support.apple.com\/kb\/ph5042\">Safari<\/a><\/span><\/p>\n<p><span>Si tiene dudas sobre esta pol\u00edtica de cookies, puede contactar con APARTAMENTOS PLAZA. en <a href=\"mailto:info@apartamentosplaza.com\">info@apartamentosplaza.com<\/a><\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cookie es un fichero que se descarga en su ordenador al acceder a determinadas p\u00e1ginas web. Las cookies permiten a una p\u00e1gina web, entre otras cosas, almacenar y recuperar informaci\u00f3n sobre los h\u00e1bitos de navegaci\u00f3n de un usuario o de su equipo y, dependiendo de la informaci\u00f3n que contengan y de la forma en que [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-647","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pol\u00edtica de Cookies - Apartamentos Plaza<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/apartamentosplaza.com\/web\/index.php\/politica-de-cookies\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pol\u00edtica de Cookies - Apartamentos Plaza\" \/>\n<meta property=\"og:description\" content=\"Cookie es un fichero que se descarga en su ordenador al acceder a determinadas p\u00e1ginas web. Las cookies permiten a una p\u00e1gina web, entre otras cosas, almacenar y recuperar informaci\u00f3n sobre los h\u00e1bitos de navegaci\u00f3n de un usuario o de su equipo y, dependiendo de la informaci\u00f3n que contengan y de la forma en que [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/apartamentosplaza.com\/web\/index.php\/politica-de-cookies\/\" \/>\n<meta property=\"og:site_name\" content=\"Apartamentos Plaza\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/apartamentosplazacordoba\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/index.php\\\/politica-de-cookies\\\/\",\"url\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/index.php\\\/politica-de-cookies\\\/\",\"name\":\"Pol\u00edtica de Cookies - Apartamentos Plaza\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/#website\"},\"datePublished\":\"2018-04-24T19:19:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/index.php\\\/politica-de-cookies\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/index.php\\\/politica-de-cookies\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/index.php\\\/politica-de-cookies\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pol\u00edtica de Cookies\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/#website\",\"url\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/\",\"name\":\"Apartamentos Plaza\",\"description\":\"Apartamentos Plaza en C\u00f3rdoba\",\"publisher\":{\"@id\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/#organization\",\"name\":\"Apartamentos tur\u00edsticos Plaza\",\"url\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i1.wp.com\\\/www.apartamentosplaza.com\\\/web\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/logo_plaza_fondo_blanco.png?fit=250%2C250&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i1.wp.com\\\/www.apartamentosplaza.com\\\/web\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/logo_plaza_fondo_blanco.png?fit=250%2C250&ssl=1\",\"width\":250,\"height\":250,\"caption\":\"Apartamentos tur\u00edsticos Plaza\"},\"image\":{\"@id\":\"https:\\\/\\\/apartamentosplaza.com\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/apartamentosplazacordoba\\\/\",\"https:\\\/\\\/www.instagram.com\\\/apartamentosplazacordoba\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pol\u00edtica de Cookies - Apartamentos Plaza","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/apartamentosplaza.com\/web\/index.php\/politica-de-cookies\/","og_locale":"it_IT","og_type":"article","og_title":"Pol\u00edtica de Cookies - Apartamentos Plaza","og_description":"Cookie es un fichero que se descarga en su ordenador al acceder a determinadas p\u00e1ginas web. Las cookies permiten a una p\u00e1gina web, entre otras cosas, almacenar y recuperar informaci\u00f3n sobre los h\u00e1bitos de navegaci\u00f3n de un usuario o de su equipo y, dependiendo de la informaci\u00f3n que contengan y de la forma en que [&hellip;]","og_url":"https:\/\/apartamentosplaza.com\/web\/index.php\/politica-de-cookies\/","og_site_name":"Apartamentos Plaza","article_publisher":"https:\/\/www.facebook.com\/apartamentosplazacordoba\/","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/apartamentosplaza.com\/web\/index.php\/politica-de-cookies\/","url":"https:\/\/apartamentosplaza.com\/web\/index.php\/politica-de-cookies\/","name":"Pol\u00edtica de Cookies - Apartamentos Plaza","isPartOf":{"@id":"https:\/\/apartamentosplaza.com\/web\/#website"},"datePublished":"2018-04-24T19:19:23+00:00","breadcrumb":{"@id":"https:\/\/apartamentosplaza.com\/web\/index.php\/politica-de-cookies\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/apartamentosplaza.com\/web\/index.php\/politica-de-cookies\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/apartamentosplaza.com\/web\/index.php\/politica-de-cookies\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/apartamentosplaza.com\/web\/"},{"@type":"ListItem","position":2,"name":"Pol\u00edtica de Cookies"}]},{"@type":"WebSite","@id":"https:\/\/apartamentosplaza.com\/web\/#website","url":"https:\/\/apartamentosplaza.com\/web\/","name":"Apartamentos Plaza","description":"Apartamentos Plaza en C\u00f3rdoba","publisher":{"@id":"https:\/\/apartamentosplaza.com\/web\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/apartamentosplaza.com\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/apartamentosplaza.com\/web\/#organization","name":"Apartamentos tur\u00edsticos Plaza","url":"https:\/\/apartamentosplaza.com\/web\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/apartamentosplaza.com\/web\/#\/schema\/logo\/image\/","url":"https:\/\/i1.wp.com\/www.apartamentosplaza.com\/web\/wp-content\/uploads\/2018\/03\/logo_plaza_fondo_blanco.png?fit=250%2C250&ssl=1","contentUrl":"https:\/\/i1.wp.com\/www.apartamentosplaza.com\/web\/wp-content\/uploads\/2018\/03\/logo_plaza_fondo_blanco.png?fit=250%2C250&ssl=1","width":250,"height":250,"caption":"Apartamentos tur\u00edsticos Plaza"},"image":{"@id":"https:\/\/apartamentosplaza.com\/web\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/apartamentosplazacordoba\/","https:\/\/www.instagram.com\/apartamentosplazacordoba\/"]}]}},"_links":{"self":[{"href":"https:\/\/apartamentosplaza.com\/web\/index.php\/wp-json\/wp\/v2\/pages\/647","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/apartamentosplaza.com\/web\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/apartamentosplaza.com\/web\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/apartamentosplaza.com\/web\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/apartamentosplaza.com\/web\/index.php\/wp-json\/wp\/v2\/comments?post=647"}],"version-history":[{"count":2,"href":"https:\/\/apartamentosplaza.com\/web\/index.php\/wp-json\/wp\/v2\/pages\/647\/revisions"}],"predecessor-version":[{"id":649,"href":"https:\/\/apartamentosplaza.com\/web\/index.php\/wp-json\/wp\/v2\/pages\/647\/revisions\/649"}],"wp:attachment":[{"href":"https:\/\/apartamentosplaza.com\/web\/index.php\/wp-json\/wp\/v2\/media?parent=647"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}